{"id":30866118,"date":"2021-05-25T19:22:05","date_gmt":"2021-05-25T17:22:05","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30866118"},"modified":"2021-06-01T10:34:16","modified_gmt":"2021-06-01T08:34:16","slug":"encuentro-entre-el-rector-de-la-upo-y-el-consejero-de-universidades","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/en\/institucional\/2021\/05\/encuentro-entre-el-rector-de-la-upo-y-el-consejero-de-universidades\/","title":{"rendered":"Encuentro entre el rector de la UPO y el consejero de Universidades"},"content":{"rendered":"<figure id=\"attachment_30866116\" aria-describedby=\"caption-attachment-30866116\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30866116 size-large\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-750x422.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-750x422.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-360x203.jpg 360w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-768x432.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-600x338.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-1536x864.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/05\/visita-Consejero-Velasco-UPO-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-30866116\" class=\"wp-caption-text\">Rogelio Velasco, Jos\u00e9 A. S\u00e1nchez, Rosa M. R\u00edos, Francisco Oliva y Concepci\u00f3n Mart\u00edn durante la reuni\u00f3n en el Rectorado<\/figcaption><\/figure>\n<p>El consejero de Transformaci\u00f3n Econ\u00f3mica, Industria, Conocimiento y Universidades,<strong> Rogelio Velasco P\u00e9rez<\/strong>, acompa\u00f1ado de la secretaria general de Universidades, Investigaci\u00f3n y Tecnolog\u00eda, <strong>Rosa Mar\u00eda R\u00edos S\u00e1nchez<\/strong> , han mantenido esta tarde un encuentro con el rector de la Universidad Pablo de Olavide, <strong>Francisco Oliva Bl\u00e1zquez<\/strong>; el vicerrector de Estrategia y Planificaci\u00f3n Docente, <strong>Jos\u00e9 Antonio S\u00e1nchez Medina<\/strong>; y la gerente de la instituci\u00f3n, <strong>Concepci\u00f3n Mart\u00edn Brenes<\/strong>. En la reuni\u00f3n, los representantes de ambas instituciones han abordado detalles sobre el modelo de financiaci\u00f3n, junto a otros aspectos de inter\u00e9s como son proyectos estrat\u00e9gicos o las novedades previstas para el pr\u00f3ximo curso.<\/p>\n<p>Velasco ha subrayado que el nuevo sistema de asignaci\u00f3n de recursos pretende establecer una gu\u00eda estable para la asignaci\u00f3n equitativa de recursos que prime la excelencia y el rendimiento, que garantice la suficiencia financiera y que proporcione a las universidades la dotaci\u00f3n adecuada para el desarrollo eficiente de su funci\u00f3n social. Asimismo, ha confiado en que \u201clas reuniones que estoy manteniendo con las instituciones sirvan para aclarar cualquier inquietud o duda sobre la propuesta planteada, de manera que se pueda cerrar en breve\u201d.<\/p>\n<p>Por su parte, el rector de la UPO ha destacado la necesidad de que se genere un modelo de financiaci\u00f3n al ser \u201cuna exigencia legal que otorga seguridad jur\u00eddica\u201d. \u201cEstamos a la espera de ver c\u00f3mo se concreta en los diferentes indicadores y variables que van a determinar cu\u00e1l va a ser la financiaci\u00f3n concreta de la Universidad\u201d, ha subrayado.<\/p>\n<p>En el encuentro mantenido esta tarde, el consejero ha comprobado de primera mano la singularidad de las actuaciones que se est\u00e1n poniendo en marcha en la Universidad Pablo de Olavide, especialmente en el \u00e1mbito de la sostenibilidad, la digitalizaci\u00f3n, el compromiso social y la investigaci\u00f3n.<\/p>\n<p>En materia de sostenibilidad, Oliva ha explicado las principales l\u00edneas en las que est\u00e1 trabajando la Universidad para potenciar su campus, un modelo de compromiso medioambiental y concebido como un bien intangible para la calidad de vida de las personas.<\/p>\n<p>El proyecto de la \u2018huella de carbono 0\u2019, con el que se pretende llegar a producir la mayor cantidad de energ\u00eda propia mediante la instalaci\u00f3n de placas fotovoltaicas, la posibilidad de aumentar la superficie arb\u00f3rea del campus o la creaci\u00f3n de aulas abiertas e integradas en el entorno, son solo algunas de los proyectos tratados que ponen de manifiesto el esp\u00edritu activo y vanguardista de la Universidad.<\/p>\n<p>Asimismo, para avanzar en la mejora de la prestaci\u00f3n del servicio p\u00fablico en la sociedad 4.0, el rector de la UPO ha expuesto el proceso de tecnificaci\u00f3n de las aulas que permitir\u00e1 que 121 aulas convencionales est\u00e9n dotadas de la tecnolog\u00eda necesaria para la impartici\u00f3n de docencia dual interactiva. Este proceso de digitalizaci\u00f3n afectar\u00e1 tambi\u00e9n a los laboratorios e incluir\u00e1 actuaciones como la migraci\u00f3n Cloud Aula Virtual BB Learn, la mejora de la plataforma Blackboard Collaborate, o la sensorificaci\u00f3n de espacios para el control de aforo, entre otras acciones.<\/p>","protected":false},"excerpt":{"rendered":"<p>El consejero de Transformaci\u00f3n Econ\u00f3mica, Industria, Conocimiento y Universidades, Rogelio Velasco, acompa\u00f1ado de la secretaria general de Universidades, Investigaci\u00f3n y Tecnolog\u00eda, Rosa Mar\u00eda R\u00edos S\u00e1nchez, han mantenido esta tarde un encuentro con el rector de la Universidad Pablo de Olavide, Francisco Oliva Bl\u00e1zquez; el vicerrector de Estrategia y Planificaci\u00f3n Docente, Jos\u00e9 Antonio S\u00e1nchez Medina; y la gerente de la instituci\u00f3n, Concepci\u00f3n Mart\u00edn Brenes. En la reuni\u00f3n, los representantes de ambas instituciones han abordado detalles sobre el modelo de financiaci\u00f3n, junto a otros aspectos de inter\u00e9s como son proyectos estrat\u00e9gicos o las novedades previstas para el pr\u00f3ximo curso.<\/p>","protected":false},"author":15,"featured_media":30866116,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[7414,821,874,4021,203,7416,38,1756,7197],"class_list":["post-30866118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional","tag-consejero-de-universidades","tag-encuentro","tag-financiacion","tag-francisco-oliva-blazquez","tag-junta-de-andalucia","tag-proyectos-estrategicos","tag-rector","tag-reunion","tag-rogelio-velasco"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/30866118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/comments?post=30866118"}],"version-history":[{"count":6,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/30866118\/revisions"}],"predecessor-version":[{"id":30866124,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/30866118\/revisions\/30866124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/media\/30866116"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/media?parent=30866118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/categories?post=30866118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/tags?post=30866118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}