{"id":30891081,"date":"2026-05-13T10:46:58","date_gmt":"2026-05-13T08:46:58","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30891081"},"modified":"2026-05-13T10:53:43","modified_gmt":"2026-05-13T08:53:43","slug":"la-fundacion-de-municipios-convoca-la-vigesima-edicion-de-sus-premios-extraordinarios-de-bachillerato","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/en\/institucional\/2026\/05\/la-fundacion-de-municipios-convoca-la-vigesima-edicion-de-sus-premios-extraordinarios-de-bachillerato\/","title":{"rendered":"La Fundaci\u00f3n de Municipios convoca la vig\u00e9sima edici\u00f3n de sus Premios Extraordinarios de Bachillerato"},"content":{"rendered":"<figure id=\"attachment_30889346\" aria-describedby=\"caption-attachment-30889346\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30889346\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/12\/Premios-Bachillerato-Fund-Municipios-750x452.jpeg\" alt=\"Foto de familia de la entrega de Premios de Bachillerato\" width=\"750\" height=\"452\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/12\/Premios-Bachillerato-Fund-Municipios-750x452.jpeg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/12\/Premios-Bachillerato-Fund-Municipios-420x253.jpeg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/12\/Premios-Bachillerato-Fund-Municipios-768x463.jpeg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/12\/Premios-Bachillerato-Fund-Municipios-1536x925.jpeg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/12\/Premios-Bachillerato-Fund-Municipios-2048x1234.jpeg 2048w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/12\/Premios-Bachillerato-Fund-Municipios-1320x795.jpeg 1320w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-30889346\" class=\"wp-caption-text\">Foto de familia de estudiantes premiados en la pasada edici\u00f3n<\/figcaption><\/figure>\n<p>La Fundaci\u00f3n de Municipios Pablo de Olavide convoca una nueva edici\u00f3n del\u00a0<a href=\"https:\/\/www.upo.es\/diario\/en\/fundacionmunicipios\/premios-extraordinarios\/\">Premio Extraordinario de Bachillerato Pablo de Olavide 2025\/2026<\/a>, que este a\u00f1o cumple su vig\u00e9simo aniversario. Este galard\u00f3n anual busca <strong>reconocer el esfuerzo y el excelente rendimiento acad\u00e9mico de los estudiantes de Bachillerato en cada uno de los municipios que integran su patronato<\/strong>, con el objetivo de darles reconocimiento p\u00fablico e incentivarlos hacia la continuaci\u00f3n de estudios superiores.<\/p>\n<p>Se conceder\u00e1n un m\u00e1ximo de 19 premios. Cada uno consta de un <strong>diploma acreditativo<\/strong> y una dotaci\u00f3n econ\u00f3mica de <strong>900 euros<\/strong>. Podr\u00e1n optar a este premio los alumnos y alumnas que figuren como empadronados en su municipio a fecha de 31 de diciembre de 2025 y que hayan finalizado sus estudios de Bachillerato en los municipios de\u00a0<strong>Aldeaquemada, Arquillos, Baeza, Ca\u00f1ada Rosal, Carboneros, Dos Hermanas, Fuente Carreteros, Fuente Palmera, Guarrom\u00e1n, La Carlota, La Carolina, La Luisiana, Montiz\u00f3n, Prado del Rey, San Sebasti\u00e1n de los Ballesteros, Santa Elena y Sevilla<\/strong>.<\/p>\n<p>Las personas interesadas en participar deber\u00e1n presentar su solicitud en su respectivo Ayuntamiento entre el 1 y el 25 de septiembre de 2026. Posteriormente, cada uno de los Ayuntamientos deber\u00e1 enviar a la Fundaci\u00f3n de Municipios el candidato o candidata con mejor expediente, baremado seg\u00fan la nota obtenida en los dos cursos de Bachillerato, presentando el certificado de calificaciones y nota media expedida por el centro; tarjeta de las Pruebas de Acceso a la Universidad (PAU), donde consten las calificaciones obtenidas y fotocopia compulsada del DNI.<\/p>\n<p>La entrega de premios se realizar\u00e1 a finales de este a\u00f1o en un acto solemne que contar\u00e1 con la presencia de los premiados y premiadas, as\u00ed como representantes y autoridades de municipios que forman la Fundaci\u00f3n y de la Universidad Pablo de Olavide.<\/p>\n<p>Esta edici\u00f3n tendr\u00e1 una relevancia especial al conmemorar las dos d\u00e9cadas de historia de estos premios, consolidando el compromiso de la Fundaci\u00f3n con la formaci\u00f3n de los j\u00f3venes de sus municipios.<\/p>\n<p>La\u00a0Fundaci\u00f3n de Municipios Pablo de Olavide\u00a0es una<strong> instituci\u00f3n universitaria de \u00edndole cultural y social que est\u00e1 compuesta por los pueblos que fueron fundados por el ilustrado Pablo de Olavide:<\/strong> Aldeaquemada, Arquillos, Ca\u00f1ada Rosal, Carboneros, Fuente Carreteros, Fuente Palmera, Guarrom\u00e1n, La Carlota, La Carolina, La Luisiana, Montiz\u00f3n, Prado del Rey, San Sebasti\u00e1n de los Ballesteros y Santa Elena. Adem\u00e1s, tambi\u00e9n forman parte de esta entidad otros municipios con una vinculaci\u00f3n especial con este ilustrado peruano como Baeza, Dos Hermanas y Sevilla.<\/p>\n<p>Desde su constituci\u00f3n en el a\u00f1o 2001, esta fundaci\u00f3n tiene como principal finalidad la promoci\u00f3n y desarrollo de la relaci\u00f3n entre la vida universitaria y la local. Para ello, impulsa y fomenta actividades en apoyo del desarrollo educativo e investigador, siempre de forma complementaria al desarrollo cultural, social, t\u00e9cnico y educativo.<\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"http:\/\/www.upo.es\/diario\/en\/fundacionmunicipios\/premios-extraordinarios\/\">www.upo.es\/fundacionmunicipios\/premios-extraordinarios\/<\/a><\/p>\n<p>Fuente: Fundaci\u00f3n Universidad Pablo de Olavide<\/p>","protected":false},"excerpt":{"rendered":"<p>La Fundaci\u00f3n de Municipios Pablo de Olavide convoca una nueva edici\u00f3n del Premio Extraordinario de Bachillerato Pablo de Olavide 2025\/2026, que este a\u00f1o cumple su vig\u00e9simo aniversario. <\/p>","protected":false},"author":6,"featured_media":30889346,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[644,21,3621,58,5092],"class_list":["post-30891081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional","tag-bachillerato","tag-estudiantes","tag-fundacion-de-municipios-pablo-de-olavide","tag-premio","tag-premio-extraordinario-de-bachillerato"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/30891081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/comments?post=30891081"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/30891081\/revisions"}],"predecessor-version":[{"id":30891083,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/30891081\/revisions\/30891083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/media\/30889346"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/media?parent=30891081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/categories?post=30891081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/tags?post=30891081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}