{"id":8433805,"date":"2015-02-13T07:00:29","date_gmt":"2015-02-13T07:00:29","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=8433805"},"modified":"2015-02-13T07:09:41","modified_gmt":"2015-02-13T07:09:41","slug":"manana-en-la-upo-seminario-sobre-la-celula-solar-sensibilizada-por-colorante","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/en\/ciencia\/2015\/02\/manana-en-la-upo-seminario-sobre-la-celula-solar-sensibilizada-por-colorante\/","title":{"rendered":"Hoy en la UPO, seminario sobre la c\u00e9lula solar sensibilizada por colorante"},"content":{"rendered":"<figure id=\"attachment_843380\" aria-describedby=\"caption-attachment-843380\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/en\/ciencia\/2015\/02\/manana-en-la-upo-seminario-sobre-la-celula-solar-sensibilizada-por-colorante\/attachment\/celula-solar-2\/\" rel=\"attachment wp-att-8433807\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-8433807\" title=\"T\u00e9cnico sosteniendo una c\u00e9lula solar\" alt=\"T\u00e9cnico sosteniendo una c\u00e9lula solar\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2015\/02\/celula-solar1-320x220.jpg\" width=\"320\" height=\"220\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2015\/02\/celula-solar1-320x220.jpg 320w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2015\/02\/celula-solar1-600x414.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2015\/02\/celula-solar1.jpg 800w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-843380\" class=\"wp-caption-text\">T\u00e9cnico sosteniendo una c\u00e9lula solar<\/figcaption><\/figure>\n<p>Hoy viernes <strong>13 de febrero<\/strong>, a las <strong>12:30 horas<\/strong>, en el <strong>edificio 47, segunda planta (laboratorio Nautilus)<\/strong> de la Universidad Pablo de Olavide, tendr\u00e1 lugar un seminario en el que <strong>Anna Todinova<\/strong>, profesora del Instituto de F\u00edsica Bioqu\u00edmica de la Academia Rusa de Ciencias (Mosc\u00fa), hablar\u00e1 sobre la <em><strong>dye-sensitized solar cell (DSSC) o c\u00e9lula solar sensibilizada por colorante<\/strong>.<\/em><\/p>\n<p><em>\u00a0<\/em><em>La DSSC<\/em><em>, inventada por el qu\u00edmico suizo <\/em>Michael Gr\u00e4tzel en 1991 y galardonado con el Premio Nobel de Tecnolog\u00eda en 2010, es un tipo de tecnolog\u00eda que convierte la radiaci\u00f3n solar en energ\u00eda el\u00e9ctrica y que puede llevarse a cabo a bajo coste y con un proceso de fabricaci\u00f3n simple.<\/p>\n<p>En su conferencia, Anna Todinova analizar\u00e1 las diferentes caracter\u00edsticas de la DSSC, ventajas que ofrece esta tecnolog\u00eda, alternativas para mejorarla e investigaciones que se est\u00e1n realizando recientemente. El seminario estar\u00e1 organizado por el \u00c1rea de qu\u00edmica-f\u00edsica de la UPO y la entrada ser\u00e1 libre y gratuita hasta completar aforo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Hoy  viernes 13 de febrero, a las 12:30 horas, en el edificio 47, segunda planta (laboratorio Nautilus) de la Universidad Pablo de Olavide, tendr\u00e1 lugar un seminario en el que Anna Todinova, profesora del Instituto de F\u00edsica Bioqu\u00edmica de la Academia Rusa de Ciencias (Mosc\u00fa), hablar\u00e1 sobre la dye-sensitized solar cell (DSSC) o c\u00e9lula solar sensibilizada por colorante.<\/p>","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[2142,2141],"class_list":["post-8433805","post","type-post","status-publish","format-standard","hentry","category-ciencia","tag-celula-solar-sensibilizada-por-colorante","tag-dye-sensitized-solar-cell-dssc"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/8433805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/comments?post=8433805"}],"version-history":[{"count":4,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/8433805\/revisions"}],"predecessor-version":[{"id":8433810,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/posts\/8433805\/revisions\/8433810"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/media?parent=8433805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/categories?post=8433805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/en\/wp-json\/wp\/v2\/tags?post=8433805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}