{"id":11748032,"date":"2016-01-13T12:10:03","date_gmt":"2016-01-13T12:10:03","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=11748032"},"modified":"2016-01-13T12:10:03","modified_gmt":"2016-01-13T12:10:03","slug":"sobresaliente-cum-laude-para-la-tesis-la-formacion-y-el-desarrollo-de-competencias-para-el-uso-didactico-de-las-tic-de-los-profesores-universitarios-el-entorno-virtual-como-herramienta-de-ca","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/tesis\/2016\/01\/sobresaliente-cum-laude-para-la-tesis-la-formacion-y-el-desarrollo-de-competencias-para-el-uso-didactico-de-las-tic-de-los-profesores-universitarios-el-entorno-virtual-como-herramienta-de-ca\/","title":{"rendered":"Sobresaliente Cum Laude para la tesis \u201cLa formaci\u00f3n y el desarrollo de competencias para el uso did\u00e1ctico de las TIC de los profesores universitarios. El entorno virtual como herramienta de cambio\u201d"},"content":{"rendered":"<p>Ayer martes tuvo lugar en la sala de grados del edificio 45 la defensa p\u00fablica de la tesis doctoral titulada \u201cLa formaci\u00f3n y el desarrollo de competencias para el uso did\u00e1ctico de las TIC de los profesores universitarios. El entorno virtual como herramienta de cambio\u201d, de la que es autora Karla Mart\u00ednez Flores. Esta tesis doctoral, dirigida por los profesores Julio Cabero Almenara de la Universidad de Sevilla y Luisa Torres Barzabal de la Universidad Pablo de Olavide, ha obtenido la calificaci\u00f3n de Sobresaliente Cum Laude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer martes tuvo lugar en la sala de grados del edificio 45 la defensa p\u00fablica de la tesis doctoral titulada \u201cLa formaci\u00f3n y el desarrollo de competencias para el uso did\u00e1ctico de las TIC de los profesores universitarios. El entorno virtual como herramienta de cambio\u201d, de la que es autora Karla Mart\u00ednez Flores. Esta tesis doctoral, dirigida por los profesores Julio Cabero Almenara de la Universidad de Sevilla y Luisa Torres Barzabal de la Universidad Pablo de Olavide, ha obtenido la calificaci\u00f3n de Sobresaliente Cum Laude.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[119],"tags":[2902,2920,465,2921,217,719],"class_list":["post-11748032","post","type-post","status-publish","format-standard","hentry","category-tesis","tag-competencias","tag-docencia-universitaria","tag-educacion","tag-entorno-virtual","tag-nuevas-tecnologias","tag-tic"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/11748032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=11748032"}],"version-history":[{"count":1,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/11748032\/revisions"}],"predecessor-version":[{"id":11748033,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/11748032\/revisions\/11748033"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=11748032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=11748032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=11748032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}