{"id":11817271,"date":"2016-01-19T10:56:08","date_gmt":"2016-01-19T10:56:08","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=11817271"},"modified":"2016-01-19T10:56:08","modified_gmt":"2016-01-19T10:56:08","slug":"sobresaliente-cum-laude-para-la-tesis-diseno-y-validacion-de-una-herramienta-para-valorar-el-grado-de-satisfaccion-en-la-implantacion-de-un-programa-de-promocion-deportiva-estudio-de-caso","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/tesis\/2016\/01\/sobresaliente-cum-laude-para-la-tesis-diseno-y-validacion-de-una-herramienta-para-valorar-el-grado-de-satisfaccion-en-la-implantacion-de-un-programa-de-promocion-deportiva-estudio-de-caso\/","title":{"rendered":"Sobresaliente Cum Laude para la tesis \u201cDise\u00f1o y validaci\u00f3n de una herramienta para valorar el grado de satisfacci\u00f3n en la implantaci\u00f3n de un programa de promoci\u00f3n deportiva. Estudio de caso: \u201cVuela con el b\u00e1dminton\u201d (Andaluc\u00eda)\u201d"},"content":{"rendered":"<p>Ayer lunes tuvo lugar en la sala de tesis del edificio 45 la defensa p\u00fablica de la tesis doctoral titulada \u201cDise\u00f1o y validaci\u00f3n de una herramienta para valorar el grado de satisfacci\u00f3n en la implantaci\u00f3n de un programa de promoci\u00f3n deportiva. Estudio de caso: \u201cVuela con el b\u00e1dminton\u201d (Andaluc\u00eda)\u201d, de la que es autor Nicol\u00e1s Fern\u00e1ndez Mart\u00ednez. Esta tesis doctoral, dirigida por los profesores Alberto Nuviala Nuviala y Antonio Fern\u00e1ndez Mart\u00ednez de la Universidad Pablo de Olavide, ha obtenido la calificaci\u00f3n de Sobresaliente Cum laude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer lunes tuvo lugar en la sala de tesis del edificio 45 la defensa p\u00fablica de la tesis doctoral titulada \u201cDise\u00f1o y validaci\u00f3n de una herramienta para valorar el grado de satisfacci\u00f3n en la implantaci\u00f3n de un programa de promoci\u00f3n deportiva. Estudio de caso: \u201cVuela con el b\u00e1dminton\u201d (Andaluc\u00eda)\u201d, de la que es autor Nicol\u00e1s Fern\u00e1ndez Mart\u00ednez. Esta tesis doctoral, dirigida por los profesores Alberto Nuviala Nuviala y Antonio Fern\u00e1ndez Mart\u00ednez de la Universidad Pablo de Olavide, ha obtenido la calificaci\u00f3n de Sobresaliente Cum laude.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[119],"tags":[190,577,541,2853],"class_list":["post-11817271","post","type-post","status-publish","format-standard","hentry","category-tesis","tag-andalucia","tag-badminton","tag-deporte","tag-satisfaccion"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/11817271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=11817271"}],"version-history":[{"count":1,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/11817271\/revisions"}],"predecessor-version":[{"id":11817273,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/11817271\/revisions\/11817273"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=11817271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=11817271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=11817271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}