{"id":12461350,"date":"2016-03-09T13:06:11","date_gmt":"2016-03-09T13:06:11","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=12461350"},"modified":"2016-03-11T07:49:51","modified_gmt":"2016-03-11T07:49:51","slug":"la-upo-apoya-el-arte-y-la-cultura-emergente-a-traves-de-la-programacion-cultura-minima","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/cultura\/2016\/03\/la-upo-apoya-el-arte-y-la-cultura-emergente-a-traves-de-la-programacion-cultura-minima\/","title":{"rendered":"La UPO apoya el arte y la cultura emergente a trav\u00e9s de la programaci\u00f3n \u201cCultura M\u00ednima\u201d"},"content":{"rendered":"<figure id=\"attachment_12461361\" aria-describedby=\"caption-attachment-12461361\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-05.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-12461361\" alt=\"El rector Vicente Guzm\u00e1n y Elodia Hern\u00e1ndez, Vicerrectora de Cultura y Compromiso Social, en la presentaci\u00f3n del programa Cultura M\u00ednima junto a artistas participantes\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-05-600x358.jpg\" width=\"600\" height=\"358\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-05-600x358.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-05-320x191.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><figcaption id=\"caption-attachment-12461361\" class=\"wp-caption-text\">El rector Vicente Guzm\u00e1n y Elodia Hern\u00e1ndez (centro), Vicerrectora de Cultura y Compromiso Social, en la presentaci\u00f3n del programa Cultura M\u00ednima junto a artistas participantes<\/figcaption><\/figure>\n<p>El rector de la Universidad Pablo de Olavide, Vicente Guzm\u00e1n Fluja, y la vicerrectora de Cultura y Compromiso Social, Elodia Hern\u00e1ndez Le\u00f3n, han presentado en la ma\u00f1ana de hoy mi\u00e9rcoles la programaci\u00f3n de <b>\u201cCultura M\u00ednima\u201d<\/b>, espacio para el arte y la cultura emergente en esta universidad que engloba m\u00fasica, literatura y teatro.<\/p>\n<figure id=\"attachment_12461351\" aria-describedby=\"caption-attachment-12461351\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-03.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12461351\" alt=\"el rector de la UPO Vicente Guzm\u00e1n Fluja junto a la vicerrectora de Cultura y Compromiso Social, Elodia Hern\u00e1ndez Le\u00f3n, en un momento de la presentaci\u00f3n\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-03-320x180.jpg\" width=\"320\" height=\"180\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-03-320x180.jpg 320w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/03\/Cultura-Minima-2016-03-600x338.jpg 600w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-12461351\" class=\"wp-caption-text\">El rector Vicente Guzm\u00e1n junto a la vicerrectora de Cultura y Compromiso Social, Elodia Hern\u00e1ndez, en un momento de la presentaci\u00f3n<\/figcaption><\/figure>\n<p>A trav\u00e9s de este programa, la Universidad Pablo de Olavide ofrece el Espacio Cultural Antigua Guarder\u00eda (ECAG), as\u00ed como equipamiento t\u00e9cnico, apoyo al montaje y comunicaci\u00f3n, \u201cpara dar visibilidad a artistas y agrupaciones emergentes, pertenezcan o no a la comunidad universitaria\u201d, explica la vicerrectora Elodia Hern\u00e1ndez, quien ha a\u00f1adido que \u201ceste formato de microcultura responde a una concepci\u00f3n art\u00edstica m\u00e1s cercana, una idea modesta y singular pero con mucha proyecci\u00f3n\u201d. Por su parte, el rector de la UPO, Vicente Guzm\u00e1n, ha subrayado \u201cla importante funci\u00f3n que tiene la cultura como transmisora de valores y elemento de transformaci\u00f3n, concienciaci\u00f3n y pensamiento cr\u00edtico\u201d. En este sentido, ha recalcado el compromiso que tiene la Universidad Pablo de Olavide en apoyo a las acciones culturales, que se materializa, entre otras cosas, a trav\u00e9s de esta programaci\u00f3n.<\/p>\n<p>De esta manera, desde el 10 de marzo hasta el 24 de noviembre se han programado un total de diez acciones acogiendo as\u00ed propuestas art\u00edsticas de diferentes disciplinas como teatro, recitales de poes\u00eda, presentaciones de libros o conciertos de agrupaciones musicales de diferentes estilos.<\/p>\n<p>La programaci\u00f3n comenzar\u00e1 ma\u00f1ana jueves 10 de marzo, a las 19:30 horas, con m\u00fasica en directo a cargo de <b>Mr. Maro<\/b>, grupo que ofrecer\u00e1 canciones propias en espa\u00f1ol, mezclando diferentes estilos como pop, reggae o influencias flamencas. Para el 31 de marzo hay dos propuestas de teatro m\u00ednimo: <b>\u201cAmores que matan nunca mueren\u201d<\/b>, de la compa\u00f1\u00eda Rid\u00edculus Teatro, y <b>\u201cDiario de una mujer\u201d<\/b>, a cargo de Ilusa Teatro. La programaci\u00f3n contin\u00faa el 21 de abril con m\u00fasica y poes\u00eda de la mano de <b>Caye Cayetana y con Ele<\/b>. Se trata de un concierto de temas propios del grupo con flamenco, rap, reggea, bossanova, funky o pop, y jam art\u00edstica posterior abierta a toda persona que quiera participar aportando m\u00fasica, instrumental, voz, poes\u00eda, mon\u00f3logos o teatro.<\/p>\n<p>El 12 de mayo Mar\u00eda del Carmen Maestre Montes presentar\u00e1 su <b>libro \u201cSiete Cuentos. Viaja por tus emociones\u201d<\/b> y el juego de creatividad compuesto por 49 cartas ilustradas que acompa\u00f1an y narran visualmente los cuentos de que se compone el libro. El 12 de junio Luz Tr\u00edo ofrecer\u00e1 su <b>concierto \u201cBloos, Blooze, Blues\u201d,<\/b> donde har\u00e1n alusi\u00f3n a este blues que mantiene la esencia de sus ra\u00edces africanas mientras se fusiona con diversos estilos y g\u00e9neros a lo largo de la Historia.<\/p>\n<p>El 13 de octubre el Coro de la Universidad Pablo de Olavide ofrecer\u00e1 el <b>concierto \u201cM\u00fasica en la Espa\u00f1a e Inglaterra de Cervantes y Shakespeare\u201d<\/b> a trav\u00e9s del cual\u00a0 dar\u00e1n a conocer la m\u00fasica de la \u00e9poca a la vez que rendir\u00e1n homenaje a estos dos personajes ilustres. El 27 de octubre la Asociaci\u00f3n Cultural Letras y Escenas presenta su obra <b>\u201cLa feria de los Homo Sapiens\u201d, <\/b>obra teatral escrita en clave de humor basada en las ferias ambulantes del siglo XIX.<\/p>\n<p>El 10 de noviembre, Travieso Quartet ofrecer\u00e1 su concierto <b>\u201cJazz or Not: M\u00fasica Bastarda Vol 2\u201d<\/b>, segunda muestra del amplio abanico de ritmos que gravitan en torno al jazz, como swing, funk, blues, latin, soul, rock o bossa nova. Completa la programaci\u00f3n, el 24 de noviembre, el Coro de la Universidad Pablo de Olavide con su concierto <b>\u201cLa m\u00fasica en la pen\u00ednsula Ib\u00e9rica hasta 1492. M\u00fasica de las tres culturas\u201d<\/b>, con cuarteto de voces e instrumentos antiguos.<\/p>\n<p>Las entradas, que tienen un precio de 3 a 5 euros, se pondr\u00e1n a la venta a partir de las 18:00 horas el mismo d\u00eda de la actuaci\u00f3n en el Espacio Cultural Antigua Guarder\u00eda (ECAG) de la Universidad Pablo de Olavide, que se convierte en as\u00ed en espacio estable de la programaci\u00f3n cultural de esta universidad. Adem\u00e1s, el ECAG acoge el trabajo diario de las agrupaciones que conforman el Programa Artes y Formaci\u00f3n del Vicerrectorado de Cultura y Participaci\u00f3n Social, como el Aula de Artes Esc\u00e9nicas, Coro de la UPO, Pe\u00f1a Universitaria \u201cSentir Flamenco\u201d y la colaboraci\u00f3n desde hace a\u00f1os con el Coro South Gospel de Sevilla.<\/p>\n<p><strong>&gt;\u00a0<a href=\"https:\/\/www.upo.es\/upsc\/export\/sites\/upsc\/Documentos\/extension\/Documentos\/Programacixn15-16b.pdf\">PROGRAMACI\u00d3N \u201cCULTURA M\u00cdNIMA\u201d<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rector Vicente Guzm\u00e1n, y la vicerrectora de Cultura y Compromiso Social, Elodia Hern\u00e1ndez, han presentado la programaci\u00f3n de \u201cCultura M\u00ednima\u201d, espacio para el arte y la cultura emergente en esta universidad que engloba m\u00fasica, literatura y teatro.  A trav\u00e9s de este programa, la Universidad Pablo de Olavide ofrece el Espacio Cultural Antigua Guarder\u00eda (ECAG), as\u00ed como equipamiento t\u00e9cnico, apoyo al montaje y comunicaci\u00f3n, \u201cpara dar visibilidad a artistas y agrupaciones emergentes, pertenezcan o no a la comunidad universitaria\u201d.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[7],"tags":[71,747,75,402,334,38,95,106],"class_list":["post-12461350","post","type-post","status-publish","format-standard","hentry","category-cultura","tag-coro","tag-elodia-hernandez","tag-extension-cultural","tag-musica","tag-presentacion","tag-rector","tag-teatro","tag-vicente-c-guzman"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/12461350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=12461350"}],"version-history":[{"count":7,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/12461350\/revisions"}],"predecessor-version":[{"id":12486888,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/12461350\/revisions\/12486888"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=12461350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=12461350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=12461350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}