{"id":1762574,"date":"2013-10-14T06:00:24","date_gmt":"2013-10-14T06:00:24","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=1762574"},"modified":"2013-10-14T06:16:09","modified_gmt":"2013-10-14T06:16:09","slug":"nuestro-objetivo-es-orientar-al-estudiante-para-una-futura-dedicacion-profesional-en-temas-de-internacionalizacion","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/entrevista\/2013\/10\/nuestro-objetivo-es-orientar-al-estudiante-para-una-futura-dedicacion-profesional-en-temas-de-internacionalizacion\/","title":{"rendered":"\u00abNuestro objetivo es orientar al estudiante para una futura dedicaci\u00f3n profesional en temas de internacionalizaci\u00f3n\u00bb"},"content":{"rendered":"<figure id=\"attachment_1762577\" aria-describedby=\"caption-attachment-1762577\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/10\/jmberbel1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1762577\" alt=\"Juan Manuel Berbel Pineda, profesor titular del Departamento de Organizaci\u00f3n de Empresas y Marketing y director de la C\u00e1tedra Extenda de Internacionalizaci\u00f3n de la UPO.\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/10\/jmberbel1-320x213.jpg\" width=\"320\" height=\"213\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/10\/jmberbel1-320x213.jpg 320w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/10\/jmberbel1-1024x682.jpg 1024w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/10\/jmberbel1-600x400.jpg 600w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-1762577\" class=\"wp-caption-text\">Juan Manuel Berbel Pineda es profesor titular del Departamento de Organizaci\u00f3n de Empresas y Marketing y director de la C\u00e1tedra Extenda de Internacionalizaci\u00f3n de la UPO.<\/figcaption><\/figure>\n<p><b>Muchos gur\u00fas econ\u00f3micos apuestan por la internacionalizaci\u00f3n de las empresas como una salida fiable a la crisis econ\u00f3mica actual, pero para llevar a cabo con \u00e9xito la aventura de la comercializaci\u00f3n exterior hay que estar preparado. Es aqu\u00ed donde juega un papel esencial la <\/b><b>C\u00e1tedra Extenda de Internacionalizaci\u00f3n de la UPO, cuyo director, el profesor Juan Manuel Berbel Pineda, nos cuenta en esta entrevista la importancia de formar a los estudiantes universitarios en la conquista de los mercados internacionales.<\/b><b>\u00a0<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>\u00bfCu\u00e1l es el objetivo de la C\u00e1tedra Extenda de Internacionalizaci\u00f3n?<\/b><\/p>\n<p>La C\u00e1tedra Extenda es una iniciativa de la <a href=\"http:\/\/www.juntadeandalucia.es\/organismos\/economiainnovacioncienciayempleo.html\">Consejer\u00eda de Econom\u00eda, Innovaci\u00f3n, Ciencia y Empleo<\/a> a trav\u00e9s de la <a href=\"http:\/\/www.extenda.es\/web\/opencms\/\">Agencia Andaluza de Promoci\u00f3n Exterior<\/a>, cuyo objetivo fundamental es orientar a los estudiantes universitarios para una futura dedicaci\u00f3n profesional en temas de internacionalizaci\u00f3n. Se trata, por tanto, de inculcar a nuestros alumnos el \u201cgusanillo\u201d de la internacionalizaci\u00f3n, haci\u00e9ndoles ver la necesidad de ser competitivos a nivel internacional, form\u00e1ndoles y prepar\u00e1ndoles para esta situaci\u00f3n, ya que los estudiantes de hoy ser\u00e1n los directivos de ma\u00f1ana.<b>\u00a0<\/b><\/p>\n<p>La C\u00e1tedra es, entonces, punto de conexi\u00f3n entre instituciones p\u00fablicas, empresas y universidad, para contribuir a la mejora de la internacionalizaci\u00f3n de la econom\u00eda andaluza.<b>\u00a0<\/b><\/p>\n<p><b>\u00bfDesde cu\u00e1ndo se imparte esta c\u00e1tedra en la Universidad Pablo de Olavide?<\/b><b>\u00a0<\/b><\/p>\n<p>En 2003 la Agencia Andaluza de Promoci\u00f3n Exterior, adscrita entonces a la Consejer\u00eda de Turismo, Comercio y Deporte, firma un convenio con la UPO, siendo la primera universidad que se adhiere a esta iniciativa. El modelo de trabajo aqu\u00ed iniciado se fue exportando al resto de universidades y actualmente todas las universidades andaluzas forman parte de este proyecto, teniendo cada una gesti\u00f3n independiente en el desarrollo de sus actividades pero buscando las sinergias que hagan que todas est\u00e9n conectas en torno al objetivo com\u00fan, formando una Red de C\u00e1tedras.<\/p>\n<p><b>\u00bfQu\u00e9 actividades se llevan a cabo desde esta universidad?<\/b><b>\u00a0<\/b><\/p>\n<p>La c\u00e1tedra es un foro en el que se llevan a cabo actividades acad\u00e9micas e investigadoras en el campo de la internacionalizaci\u00f3n. Respecto a las actividades acad\u00e9micas, llevamos a cabo la realizaci\u00f3n de seminarios en los que acercamos la empresa a los alumnos y tambi\u00e9n propiciamos que estas empresas se acerquen a la universidad. As\u00ed, invitamos a empresarios relevantes andaluces para que cuenten su experiencia, realizamos talleres pr\u00e1cticos, ciclos de conferencias y visitamos las empresas andaluzas m\u00e1s destacadas.<\/p>\n<p>Estas actividades acad\u00e9micas se enmarcaban en una actividad de libre configuraci\u00f3n que se extingui\u00f3 con la implantaci\u00f3n del Plan Bolonia, por lo que nos hemos tenido que reinventar y llevarlas a cabo en el marco de distintos m\u00e1steres de la UPO: el M\u00e1ster en Direcci\u00f3n de Negocios Internacionales, M\u00e1ster MBA en Direcci\u00f3n y Organizaci\u00f3n de Empresas, M\u00e1ster en Direcci\u00f3n Estrat\u00e9gica en Recursos Humanos y el M\u00e1ster de Direcci\u00f3n en Licitaciones Internacionales, donde Extenda no s\u00f3lo colabora sino que tambi\u00e9n es coorganizadora.<b>\u00a0<\/b><\/p>\n<p><b>\u00bfMe puede hablar de la actividad investigadora?<\/b><b>\u00a0<\/b><\/p>\n<p>Extenda pide a las universidades que lleven a cabo estudios que les sean relevantes. Entre otras cosas, hemos colaborado en un libro de casos de empresas andaluzas internacionalizadas, hemos realizado un estudio sobre el tejido empresarial de Sevilla para ver su potencial de internacionalizaci\u00f3n, y hemos participado en la elaboraci\u00f3n del \u00a0\u201cIV Plan para la Internacionalizaci\u00f3n de la Econom\u00eda Andaluza, 2010-2013\u201d.<b>\u00a0<\/b><\/p>\n<p><b>\u00bfQu\u00e9 proyectos tiene previsto poner en marcha?<\/b><b>\u00a0<\/b><\/p>\n<p>La c\u00e1tedra est\u00e1 vinculada al Departamento de Organizaci\u00f3n de Empresas y Marketing y, por tanto, a la Facultad de Empresariales. Uno de los objetivos que nos marcamos ha sido abrirla al resto de departamentos o facultades de esta universidad, y en \u00e9l estamos trabajando. De hecho, ya han colaborado con la C\u00e1tedra el Departamento de Trabajo Social y Servicios Sociales, el Departamento de Derecho Privado, el Departamento de Econom\u00eda Financiera y Contabilidad, o el de Filolog\u00eda y Traducci\u00f3n, entre otros.<b>\u00a0<\/b><\/p>\n<p><b>Uno de los atractivos de la Agencia Andaluza de Promoci\u00f3n Exterior son sus becas \u00bfQu\u00e9 ofrecen a los estudiantes?<\/b><b>\u00a0<\/b><\/p>\n<p>La Agencia Andaluza de Promoci\u00f3n Exterior convoca anualmente becas de formaci\u00f3n en comercio internacional y es de destacar que la Universidad Pablo de Olavide siempre ha contado con alumnos seleccionados en todas las convocatorias, e incluso han copado los primeros puestos.\u00a0 Estas becas tienen una duraci\u00f3n de 24 meses. La primera fase de realizaci\u00f3n de pr\u00e1cticas se desarrolla en una de las oficinas que Extenda tiene en distintas ciudades del mundo como Tokio, Buenos Aires, Sao Paulo o Londres. La segunda fase se desarrolla en una empresa andaluza u otra entidad p\u00fablica o privada cuya actividad est\u00e9 relacionada con el comercio internacional.<b>\u00a0<\/b><\/p>\n<p><b>En la situaci\u00f3n de crisis en la que nos encontramos \u00bfla soluci\u00f3n es, entonces, salir al exterior?<\/b><b>\u00a0<\/b><\/p>\n<p>Por supuesto. Ahora que el mercado espa\u00f1ol no se mueve, las empresas est\u00e1n como locas saliendo fuera. Si aqu\u00ed no vendes tendr\u00e1s que buscarte otro mercado que antes, quiz\u00e1s, no ten\u00edas en cuenta. \u00bfCu\u00e1ntas empresas hay hoy en mercados como Brasil, China, India u otros mercados que antes no se consideraban?<\/p>\n<p>Un aspecto muy importante en econom\u00eda es la balanza comercial: si t\u00fa compras m\u00e1s de lo que \u00a0vendes tienes un d\u00e9ficit comercial. Lo que se quiere es revertir eso, y para que se venda m\u00e1s en el exterior tenemos que salir fuera. Se pretende entonces ganar en competitividad, ayudar a que la balanza comercial andaluza sea de super\u00e1vit, no de d\u00e9ficit. Y para ello hay que salir, y para salir hay que formar a la gente que va a tomar las decisiones. Para eso est\u00e1 la C\u00e1tedra Extenda de Internacionalizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ENTREVISTA: Muchos gur\u00fas econ\u00f3micos apuestan por la internacionalizaci\u00f3n de las empresas como una salida fiable a la crisis econ\u00f3mica actual, pero para llevar a cabo con \u00e9xito la aventura de la comercializaci\u00f3n exterior hay que estar preparado. Es aqu\u00ed donde juega un papel esencial la C\u00e1tedra Extenda de Internacionalizaci\u00f3n de la UPO, cuyo director, el profesor Juan Manuel Berbel Pineda, nos cuenta en esta entrevista la importancia de formar a los estudiantes universitarios en la conquista de los mercados internacionales.<\/p>\n","protected":false},"author":2,"featured_media":1762578,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[24],"tags":[358,63,80,66,21,925],"class_list":["post-1762574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevista","tag-catedra","tag-economia","tag-emprendedores","tag-empresa","tag-estudiantes","tag-internacionalizacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/1762574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=1762574"}],"version-history":[{"count":4,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/1762574\/revisions"}],"predecessor-version":[{"id":1782194,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/1762574\/revisions\/1782194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/1762578"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=1762574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=1762574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=1762574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}