{"id":25179287,"date":"2017-12-22T01:47:51","date_gmt":"2017-12-22T01:47:51","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=25179287"},"modified":"2017-12-22T13:51:00","modified_gmt":"2017-12-22T13:51:00","slug":"el-proyecto-flood-cba2-en-el-que-participa-la-upo-culmina-su-ultima-fase-con-exito","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/ciencia\/2017\/12\/el-proyecto-flood-cba2-en-el-que-participa-la-upo-culmina-su-ultima-fase-con-exito\/","title":{"rendered":"El proyecto Flood-CBA#2 en el que participa la UPO culmina su \u00faltima fase con \u00e9xito"},"content":{"rendered":"<figure id=\"attachment_11679680\" aria-describedby=\"caption-attachment-11679680\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/01\/high-water-876580_1280.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-11679680\" alt=\"El objetivo del proyecto FLOOD CBA#2 es el establecimiento de las medidas de prevenci\u00f3n y protecci\u00f3n m\u00e1s adecuadas en las zonas m\u00e1s propensas a sufrir inundaciones.\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/01\/high-water-876580_1280-320x240.jpg\" width=\"320\" height=\"240\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/01\/high-water-876580_1280-320x240.jpg 320w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/01\/high-water-876580_1280-600x450.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2016\/01\/high-water-876580_1280.jpg 1280w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-11679680\" class=\"wp-caption-text\">El objetivo del proyecto FLOOD CBA#2 es el establecimiento de las medidas de prevenci\u00f3n y protecci\u00f3n m\u00e1s adecuadas en las zonas m\u00e1s propensas a sufrir inundaciones<\/figcaption><\/figure>\n<p>El <strong>proyecto \u201cFlood-CBA#2\u201d<\/strong>, centrado en la integraci\u00f3n del an\u00e1lisis coste-beneficio en los procesos de toma de decisiones para seleccionar las normas de protecci\u00f3n adecuadas en zonas inundables, ha finalizado con un notable impacto en los pa\u00edses involucrados. Financiado por la Direcci\u00f3n General de Ayuda Humanitaria y Protecci\u00f3n Civil \u00a0(DG ECHO) de la Uni\u00f3n Europea, se puso en marcha en enero de 2016 con una duraci\u00f3n de dos a\u00f1os. En la iniciativa \u2013impulsada por un consorcio de entidades procedentes de Grecia, Reino Unido, Portugal y Espa\u00f1a\u2013, ha participado la Universidad Pablo de Olavide con la aportaci\u00f3n de los investigadores <strong>F\u00e1tima Navas<\/strong> \u2013responsable del proyecto en la UPO\u2013, <strong>Gonzalo Malv\u00e1rez<\/strong> \u2013responsable del \u00c1rea de Geograf\u00eda F\u00edsica\u2013, y <strong>Gerard Mor\u00e9<\/strong>, todos miembros del grupo de investigaci\u00f3n \u201cCoastal Environments\u201d.<\/p>\n<p>La \u00faltima fase del proyecto ha culminado con una conferencia final en Alexandroupoli (Grecia) durante los d\u00edas 22 y 23 de noviembre. En esta conferencia, Gonzalo Malv\u00e1rez present\u00f3 el desarrollo de las tareas del proyecto relacionadas con el paquete de trabajo liderado por la UPO, enfocado fundamentalmente a la transferencia del conocimiento generado desde el seno del proyecto hacia actores clave en la gesti\u00f3n de la prevenci\u00f3n del riesgo de inundaciones en Europa. Tambi\u00e9n participaron en Alexandroupoli investigadores de los restantes socios del proyecto, compuesto por universidades, centros de investigaci\u00f3n y organismos p\u00fablicos: SIGMA Consultants (Grecia), FHRC (Gran Breta\u00f1a), CICS.NOVA (Portugal), Agencia de Medio Ambiente y Agua de Andaluc\u00eda REDIAM (Espa\u00f1a), Regi\u00f3n de Macedonia Este y Tracia (Grecia), y Ayuntamiento de Amadora (Portugal).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La iniciativa europea centrada en el an\u00e1lisis del coste-beneficio de las normas de protecci\u00f3n para zonas inundables finaliza tras dos a\u00f1os de trabajos en los que han participado entidades procedentes de Grecia, Reino Unido, Portugal y Espa\u00f1a.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-25179287","post","type-post","status-publish","format-standard","hentry","category-ciencia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/25179287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=25179287"}],"version-history":[{"count":1,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/25179287\/revisions"}],"predecessor-version":[{"id":25179288,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/25179287\/revisions\/25179288"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=25179287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=25179287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=25179287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}