{"id":2557171,"date":"2014-01-15T13:27:46","date_gmt":"2014-01-15T13:27:46","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=2557171"},"modified":"2014-01-15T13:27:46","modified_gmt":"2014-01-15T13:27:46","slug":"sobresaliente-cum-laude-para-la-tesis-la-ruta-de-senalizacion-notch-en-hematopoyesis-comparacion-de-la-funcion-de-notch1-en-celulas-madres-fetales-y-adultas","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/tesis\/2014\/01\/sobresaliente-cum-laude-para-la-tesis-la-ruta-de-senalizacion-notch-en-hematopoyesis-comparacion-de-la-funcion-de-notch1-en-celulas-madres-fetales-y-adultas\/","title":{"rendered":"Sobresaliente Cum Laude para la tesis \u201cLa ruta de se\u00f1alizaci\u00f3n notch en hematopoyesis: comparaci\u00f3n de la funci\u00f3n de NOTCH1 en c\u00e9lulas madres fetales y adultas\u201d"},"content":{"rendered":"<p>Hoy mi\u00e9rcoles ha tenido lugar en la sala de grados del edificio 6 la defensa p\u00fablica de la tesis doctoral titulada \u00abLa ruta de se\u00f1alizaci\u00f3n notch en hematopoyesis: comparaci\u00f3n de la funci\u00f3n de NOTCH1 en c\u00e9lulas madres fetales y adultas\u201d, de la que es autora Isabel Mar\u00eda Prados Siles. Esta tesis doctoral, dirigida por la profesora Mar\u00eda Jos\u00e9 S\u00e1nchez Sanz (CABD-CSIC), tiene como tutor en el Departamento de Biolog\u00eda Molecular e Ingenier\u00eda Bioqu\u00edmica de la Universidad Pablo de Olavide al profesor Jos\u00e9 Antonio S\u00e1nchez Alc\u00e1zar. La tesis doctoral ha obtenido la calificaci\u00f3n de Sobresaliente Cum Laude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy mi\u00e9rcoles ha tenido lugar en la sala de grados del edificio 6 la defensa p\u00fablica de la tesis doctoral titulada \u00abLa ruta de se\u00f1alizaci\u00f3n notch en hematopoyesis: comparaci\u00f3n de la funci\u00f3n de NOTCH1 en c\u00e9lulas madres fetales y adultas\u201d, de la que es autora Isabel Mar\u00eda Prados Siles. Esta tesis doctoral, dirigida por la profesora Mar\u00eda Jos\u00e9 S\u00e1nchez Sanz (CABD-CSIC), tiene como tutor en el Departamento de Biolog\u00eda Molecular e Ingenier\u00eda Bioqu\u00edmica de la Universidad Pablo de Olavide al profesor Jos\u00e9 Antonio S\u00e1nchez Alc\u00e1zar. La tesis doctoral ha obtenido la calificaci\u00f3n de Sobresaliente Cum Laude.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[119],"tags":[365,1089,1088],"class_list":["post-2557171","post","type-post","status-publish","format-standard","hentry","category-tesis","tag-celulas-madre","tag-hematopoyesis","tag-notch1"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/2557171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=2557171"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/2557171\/revisions"}],"predecessor-version":[{"id":2557173,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/2557171\/revisions\/2557173"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=2557171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=2557171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=2557171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}