{"id":2910251,"date":"2014-02-21T00:05:23","date_gmt":"2014-02-21T00:05:23","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=2910251"},"modified":"2014-02-21T08:11:43","modified_gmt":"2014-02-21T08:11:43","slug":"manana-estudiantes-de-bachillerato-del-ies-vicente-aleixandre-participan-en-la-jornada-de-ciencia-y-deporte","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/institucional\/2014\/02\/manana-estudiantes-de-bachillerato-del-ies-vicente-aleixandre-participan-en-la-jornada-de-ciencia-y-deporte\/","title":{"rendered":"Estudiantes de Bachillerato del IES Vicente Aleixandre participan hoy en la Jornada de Ciencia y Deporte"},"content":{"rendered":"<p style=\"text-align: justify;\">Un grupo de 30 estudiantes de Bachillerato del IES Vicente Aleixandre asiste hoy viernes, a las 12 horas en el aula B07 del edificio 24 de la Universidad Pablo de Olavide, a la <b>I Jornada de Ciencia y Deporte<\/b> organizada por la Facultad del Deporte de la UPO. Esta actividad tiene como objetivo dar a conocer el deporte desde su perspectiva m\u00e1s cient\u00edfica, as\u00ed como informar y orientar a los estudiantes sobre el grado en Ciencias de la Actividad F\u00edsica y del Deporte.<\/p>\n<p style=\"text-align: justify;\">Previamente, a las 11.45 horas, el decano de la Facultad del Deporte de la UPO, Antonio Fern\u00e1ndez Mart\u00ednez, dar\u00e1 la bienvenida a los estudiantes y les informar\u00e1 sobre el grado en Ciencias de la Actividad F\u00edsica del Deporte, los laboratorios de investigaci\u00f3n, as\u00ed como las investigaciones vinculadas a la Ciencias del Deporte que se est\u00e1n realizando en la Facultad.<\/p>\n<p style=\"text-align: justify;\">\u00a0Los estudiantes podr\u00e1n acercarse al deporte y a su estrecha relaci\u00f3n con la ciencia a trav\u00e9s de <span style=\"text-decoration: underline;\">cuatro talleres pr\u00e1cticos de treinta minutos de duraci\u00f3n que se realizar\u00e1n en los laboratorios del edificio 29<\/span>. Estos talleres son de \u201cSalud\u201d, donde calcular\u00e1n el porcentaje de grasa y masa muscular a trav\u00e9s de la t\u00e9cnica de bioimpedancia; \u201cEntrenamiento\u201d, en este taller se estimar\u00e1 una curva de potencia de salto; \u201cAnatom\u00eda\u201d, en el que realizar\u00e1n una prueba de osteolog\u00eda; y, por \u00faltimo, el \u00a0taller de \u201cFisiolog\u00eda\u201d, donde realizar\u00e1n una prueba de esfuerzo sobre cicloerg\u00f3metro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de 30 estudiantes de Bachillerato del IES Vicente Aleixandre asiste hoy viernes, a las 12 horas en el aula B07 del edificio 24 de la Universidad Pablo de Olavide, a la I Jornada de Ciencia y Deporte organizada por la Facultad del Deporte de la UPO. Esta actividad tiene como objetivo dar a conocer el deporte desde su perspectiva m\u00e1s cient\u00edfica, as\u00ed como informar y orientar a los estudiantes sobre el grado en Ciencias de la Actividad F\u00edsica y del Deporte.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[6],"tags":[644,1152,541,379,514,230],"class_list":["post-2910251","post","type-post","status-publish","format-standard","hentry","category-institucional","tag-bachillerato","tag-captacion","tag-deporte","tag-facultad-del-deporte","tag-jornada","tag-orientacion"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/2910251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=2910251"}],"version-history":[{"count":4,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/2910251\/revisions"}],"predecessor-version":[{"id":2915036,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/2910251\/revisions\/2915036"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=2910251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=2910251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=2910251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}