{"id":29326580,"date":"2018-11-28T19:17:29","date_gmt":"2018-11-28T19:17:29","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=29326580"},"modified":"2018-12-04T12:15:49","modified_gmt":"2018-12-04T12:15:49","slug":"crue-universidades-espanolas-presenta-el-informe-transferencia-del-conocimiento-nuevo-modelo-para-su-prestigio-e-impulso","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/institucional\/2018\/11\/crue-universidades-espanolas-presenta-el-informe-transferencia-del-conocimiento-nuevo-modelo-para-su-prestigio-e-impulso\/","title":{"rendered":"Crue Universidades Espa\u00f1olas presenta el informe \u00abTransferencia del Conocimiento: nuevo modelo para su prestigio e impulso\u00bb"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-29326581\" alt=\"2018.11.28-Informe Transferencia_ministro\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2018\/11\/2018.11.28-Informe-Transferencia_ministro-600x400.jpg\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2018\/11\/2018.11.28-Informe-Transferencia_ministro-600x400.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2018\/11\/2018.11.28-Informe-Transferencia_ministro-320x213.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/>El presidente de Crue Universidades Espa\u00f1olas, <strong>Roberto Fern\u00e1ndez,<\/strong> acudi\u00f3 hoy al acto de presentaci\u00f3n del nuevo sexenio de Transferencia celebrado en el Ministerio de Ciencia, Innovaci\u00f3n y Universidades. El ministro, <strong>Pedro Duque<\/strong>, destac\u00f3 en la apertura del acto \u00abel hito que supone unir la generaci\u00f3n de conocimiento con su transferencia\u00bb, mientras que su secretaria de Estado, <strong>\u00c1ngeles Heras<\/strong>, record\u00f3 que el nuevo tramo de evaluaci\u00f3n presentado \u00abse basa en el estudio de Crue Universidades Espa\u00f1olas\u00bb. Heras afirm\u00f3 que desde el Ministerio se ha apostado por el nuevo \u00absexenio de Transferencia\u00bb y mostr\u00f3 su agradecimiento a Salustiano Mato, vicepresidente adjunto de Crue Universidades Espa\u00f1olas y coordinador del informe presentado en el Ministerio, por haberse puesto a trabajar \u00aben tiempo r\u00e9cord\u00bb.<\/p>\n<p>En su intervenci\u00f3n, el presidente de Crue Universidades Espa\u00f1olas, Roberto Fern\u00e1ndez, record\u00f3 que \u00abla Academia debe promover la transferencia de conocimiento a la sociedad si quiere cumplir con su mandato de contribuir al bienestar de todos los ciudadanos\u00bb y que para las universidades es \u00abhist\u00f3rica la creaci\u00f3n del sexenio de transferencia\u00bb anunciado por el Gobierno.<\/p>\n<p><strong>Salustiano Mato<\/strong> fue el encargado de explicar el nuevo modelo de evaluaci\u00f3n de la Transferencia de Conocimiento basado en una serie de indicadores de capital humano, mercado y proyecci\u00f3n social que se aplicar\u00e1n en dos grandes \u00e1mbitos: el escenario institucional y el escenario individual. En este \u00faltimo escenario es donde entra de lleno el sexenio de Transferencia aprobado por el Ministerio de Ciencia, Innovaci\u00f3n y Universidades, que busca reforzar las pol\u00edticas de incentivos en las universidades y centros p\u00fablicos de investigaci\u00f3n (OPIs).<\/p>\n<p>Con esta iniciativa,<strong> Espa\u00f1a se convierte en el primer pa\u00eds en crear un modelo de evaluaci\u00f3n de este tipo<\/strong>, seg\u00fan el Ministerio. \u00abEl sistema actual no contemplaba la posibilidad de valorar adecuadamente aspectos ligados a los esfuerzos de los investigadores en el \u00e1mbito de la transferencia de los resultados del conocimiento y la innovaci\u00f3n, lo que hace que las universidades y los propios investigadores no vean plenamente reconocida su labor integral en las tres misiones universitarias (Docencia, Investigaci\u00f3n y Transferencia del Conocimiento) y en su compromiso con la sociedad y las empresas\u00bb, reconoci\u00f3 el departamento dirigido por Pedro Duque. Por eso, una de las prioridades del nuevo ministro en estos meses ha sido \u00abimpulsar mediante nuevos instrumentos la innovaci\u00f3n y la transferencia de las universidades y los OPIs a la sociedad\u00bb. A partir de ahora, los resultados de la evaluaci\u00f3n, asegura el Ministerio, podr\u00edan proporcionar a las universidades y centros de investigaci\u00f3n indicadores s\u00f3lidos y objetivos para incorporar a sus procesos de mejora de la calidad y \u00abmedir\u00bb su propio impacto social.<\/p>\n<p>Fuente: <strong>Crue Universidades Espa\u00f1olas<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de Crue Universidades Espa\u00f1olas, Roberto Fern\u00e1ndez, acudi\u00f3 al acto de presentaci\u00f3n del nuevo sexenio de Transferencia celebrado en el Ministerio de Ciencia, Innovaci\u00f3n y Universidades. El ministro, Pedro Duque, destac\u00f3 en la apertura del acto \u00abel hito que supone unir la generaci\u00f3n de conocimiento con su transferencia\u00bb, mientras que su secretaria de Estado, \u00c1ngeles Heras, record\u00f3 que el nuevo tramo de evaluaci\u00f3n presentado \u00abse basa en el estudio de Crue Universidades Espa\u00f1olas\u00bb. <\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[4124,56,199,5456,39],"class_list":["post-29326580","post","type-post","status-publish","format-standard","hentry","category-institucional","tag-crue-universidades-espanolas","tag-investigacion","tag-profesorado","tag-transferencia-del-conocimiento","tag-universidades"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/29326580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=29326580"}],"version-history":[{"count":8,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/29326580\/revisions"}],"predecessor-version":[{"id":29401429,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/29326580\/revisions\/29401429"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=29326580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=29326580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=29326580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}