{"id":30857309,"date":"2019-06-25T10:24:57","date_gmt":"2019-06-25T07:24:57","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30857309"},"modified":"2019-06-26T11:13:27","modified_gmt":"2019-06-26T08:13:27","slug":"susana-diaz-alberto-garzon-juan-marin-y-borja-semper-participan-hoy-en-el-curso-periodismo-y-politica","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/cursos-verano\/2019\/06\/susana-diaz-alberto-garzon-juan-marin-y-borja-semper-participan-hoy-en-el-curso-periodismo-y-politica\/","title":{"rendered":"Susana D\u00edaz, Alberto Garz\u00f3n, Juan Mar\u00edn y Borja S\u00e9mper participan hoy en el curso \u2018Periodismo y pol\u00edtica\u2019"},"content":{"rendered":"<figure id=\"attachment_30857311\" aria-describedby=\"caption-attachment-30857311\" style=\"width: 256px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30857311\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/06\/Susana_D\u00edaz_2018_portrait-256x360.jpg\" alt=\"\" width=\"256\" height=\"360\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/06\/Susana_D\u00edaz_2018_portrait-256x360.jpg 256w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/06\/Susana_D\u00edaz_2018_portrait-768x1080.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/06\/Susana_D\u00edaz_2018_portrait-534x750.jpg 534w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/06\/Susana_D\u00edaz_2018_portrait-600x843.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/06\/Susana_D\u00edaz_2018_portrait.jpg 976w\" sizes=\"auto, (max-width: 256px) 100vw, 256px\" \/><figcaption id=\"caption-attachment-30857311\" class=\"wp-caption-text\">Foto: Wikipedia<\/figcaption><\/figure>\n<p>Cuatro seminarios seguir\u00e1n celebr\u00e1ndose hoy martes dentro de la programaci\u00f3n de la XVII edici\u00f3n de los Cursos de Verano de la Universidad Pablo de Olavide en Carmona. En ellos, se analizar\u00e1n tem\u00e1ticas actuales y diversas, como la violencia en la adolescencia; el periodismo y la pol\u00edtica; el entendimiento entre culturas y la investigaci\u00f3n cient\u00edfico-t\u00e9cnica de los homicidios.<\/p>\n<p>El curso <strong>\u2018Periodismo y pol\u00edtica. \u00bfPoder, contrapoder o connivencia?\u2019 <\/strong>dedicar\u00e1 la jornada de ma\u00f1ana a analizar la visi\u00f3n de pol\u00edticos y periodistas. El seminario comenzar\u00e1 a las 12 horas con la conferencia de Juan Mar\u00edn, vicepresidente y consejero de Turismo, Regeneraci\u00f3n, Justicia y Administraci\u00f3n Local de la Junta de Andaluc\u00eda, que compartir\u00e1 mesa junto a la periodista de la cadena SER y tertuliana Mar\u00eda Esperanza S\u00e1nchez. Este seminario, dirigido por Rafael Rodr\u00edguez Guerrero, periodista y presidente de la Asociaci\u00f3n de la Prensa de Sevilla, se celebra en el aula 1 de la Casa Palacio de los Briones hasta el 26 de junio.<\/p>\n<p>Ya por la tarde, a las 16 horas, ser\u00e1 el turno de Alberto Garz\u00f3n, coordinador federal de Izquierda Unida, que debatir\u00e1 con la periodista y tertuliana Esther Palomera. A continuaci\u00f3n, a las 17,30 horas tomar\u00e1 el relevo la expresidenta de la Junta de Andaluc\u00eda y secretaria del PSOE de Andaluc\u00eda Susana D\u00edaz, quien mantendr\u00e1 una charla con Teodoro Le\u00f3n Gross, periodista y profesor titular en la Universidad de M\u00e1laga.<\/p>\n<p>Por \u00faltimo, la jornada de ma\u00f1ana finalizar\u00e1 con Borja S\u00e9mper, portavoz del Grupo Popular en el Parlamento Vasco y presidente del PP de Guip\u00fazcoa, que compartir\u00e1 mesa con la periodista de El Mundo y tertuliana Esther Palomera a partir de las 19 horas.<\/p>\n<p>Por otro lado, hoy tambi\u00e9n se sigue celebrando en el aula 4 de la sede Olavide en Carmona el curso <strong>\u2018Magreb, Oriente Medio y Europa: entendimiento entre culturas. Relaciones y desaf\u00edos\u2019<\/strong>, dirigido por Javier Fern\u00e1ndez Arribas, director de Atalayar.<\/p>\n<p>La jornada del martes se centrar\u00e1 en el desarrollo y la inmigraci\u00f3n. A las 9,30 horas se celebrar\u00e1 la conferencia \u201cPuntos conflictivos y espacios de encuentro entre las dos orillas\u201d, que ser\u00e1 impartida por Pedro Canales, periodista experto en el Magreb.<\/p>\n<p>El curso proseguir\u00e1 a las 10,30 horas con la conferencia \u201cMovimientos migratorios\u201d, que correr\u00e1 a cargo de Javier Mart\u00edn Dom\u00ednguez, presidente del Club Internacional de Prensa, mientras que a las 12 horas Federico Aznar, analista principal del Instituto Espa\u00f1ol de Estudios Estrat\u00e9gicos, impartir\u00e1 la ponencia \u201cRumbo al sur\u201d.<\/p>\n<p>Ya por la tarde, el seminario se retomar\u00e1 a las 16 horas con la mesa redonda \u201cComunicaci\u00f3n entre culturas. Promoci\u00f3n de lazos culturales\u201d, en la que intervendr\u00e1n Javier Mart\u00edn Dom\u00ednguez, presidente del Club Internacional de Prensa y Jos\u00e9 Mar\u00eda Pered\u00f3, catedr\u00e1tico de Comunicaci\u00f3n y Pol\u00edtica Internacional de la Universidad Europea de Madrid.<\/p>\n<p>Por otro lado, el curso <strong>\u2018Violencia en la adolescencia: filioparental, de g\u00e9nero y acoso escolar\u2019<\/strong>, dirigido por la antrop\u00f3loga y pedagoga Cosette Franco Mu\u00f1oz, comenzar\u00e1 ma\u00f1ana a las 10 horas en el aula 4 con el taller \u201cPrevenci\u00f3n de relaciones t\u00f3xicas entre j\u00f3venes\u201d, que ser\u00e1 impartida por la directora del curso. A las 12,30 horas proseguir\u00e1 la jornada Noelia Garc\u00eda, del Instituto Andaluz de la Mujer de M\u00e1laga, quien impartir\u00e1 el taller \u201cApoyar a la joven que sufre de violencia de g\u00e9nero\u201d.<\/p>\n<p>Para concluir, a las 16 horas, Juan Ignacio Paz, psic\u00f3logo del Instituto Andaluz de la Mujer especialista en violencia de g\u00e9nero, ofrecer\u00e1 el taller \u201cViolencia de g\u00e9nero en la adolescencia\u201d.<\/p>\n<p>Ya por la tarde, a las 16,30 horas, el curso concluir\u00e1 su jornada con la conferencia \u2018Aportaciones desde la disciplina urban\u00edstica en el nuevo marco urban\u00edstico de Andaluc\u00eda\u2019, que ser\u00e1 impartida por Eva Mar\u00eda Gamero Ruiz, inspectora y jefa del \u00c1rea de Ordenaci\u00f3n del Territorio y Urbanismo de la Consejer\u00eda de Medio Ambiente y Ordenaci\u00f3n del Territorio.<\/p>\n<p>Por \u00faltimo, hoy finaliza el curso <strong>\u2018Investigaci\u00f3n cient\u00edfico-t\u00e9cnica de los homicidios en el anciano, el ni\u00f1o y la mujer\u2019<\/strong>, que se celebra en el aula 6. A las 09,00 horas comenzar\u00e1 la conferencia denominada \u201cFeminicidio. Investigaci\u00f3n m\u00e9dico-legal\u201d, que estar\u00e1 a cargo del m\u00e9dico forense Mario Blanco Rodr\u00edguez, jefe del Servicio de Laboratorio del Instituto de Medicina Legal y Ciencias Forenses de Sevilla. A continuaci\u00f3n, a las 10 horas, Guillermo Repetto Kuhn, profesor del Departamento de Biolog\u00eda y Bioqu\u00edmica Molecular de la Universidad Pablo de Olavide, explicar\u00e1 la \u201cSituaci\u00f3n internacional de los homicidios en el anciano, el ni\u00f1o y la mujer\u201d.<\/p>\n<p>El seminario proseguir\u00e1 con la ponencia \u2018La intervenci\u00f3n del Instituto Nacional de Toxicolog\u00eda y Ciencias Forenses en la investigaci\u00f3n de homicidios en el anciano, el ni\u00f1o y la mujer. El Laboratorio de Histopatolog\u00eda Forense\u2019, que impartir\u00e1 Manuel Salguero Villadiego, director del Instituto Nacional de Toxicolog\u00eda y Ciencias Forenses de Sevilla.<\/p>\n<p>La \u00faltima conferencia del curso, que comenzar\u00e1 a las 12,30 horas, estar\u00e1 impartida por Carmen Jurado Montoro, jefa del Servicio de Qu\u00edmica y Toxicolog\u00eda del Instituto Nacional de Toxicolog\u00eda y Ciencias Forenses de Sevilla, que llevar\u00e1 por nombre \u201cEl laboratorio de qu\u00edmica-toxicolog\u00eda en la investigaci\u00f3n de homicidios en el anciano, el ni\u00f1o y la mujer\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuatro seminarios seguir\u00e1n celebr\u00e1ndose hoy martes dentro de la programaci\u00f3n de la XVII edici\u00f3n de los Cursos de Verano de la Universidad Pablo de Olavide en Carmona. En ellos, se analizar\u00e1n tem\u00e1ticas actuales y diversas, como la violencia en la adolescencia; el periodismo y la pol\u00edtica; el entendimiento entre culturas y la investigaci\u00f3n cient\u00edfico-t\u00e9cnica de los homicidios.<\/p>\n","protected":false},"author":6,"featured_media":30857311,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[729],"tags":[1141,532,687,76,143],"class_list":["post-30857309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-verano","tag-adolescencia","tag-criminologia","tag-periodismo","tag-politica","tag-violencia"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30857309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30857309"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30857309\/revisions"}],"predecessor-version":[{"id":30857312,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30857309\/revisions\/30857312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30857311"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30857309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30857309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30857309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}