{"id":30857393,"date":"2019-07-01T05:56:56","date_gmt":"2019-07-01T02:56:56","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30857393"},"modified":"2019-07-01T11:00:52","modified_gmt":"2019-07-01T08:00:52","slug":"la-escritora-almudena-grandes-y-la-periodista-pepa-bueno-estaran-en-el-curso-sobre-mujeres-en-el-conocimiento","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/cursos-verano\/2019\/07\/la-escritora-almudena-grandes-y-la-periodista-pepa-bueno-estaran-en-el-curso-sobre-mujeres-en-el-conocimiento\/","title":{"rendered":"La escritora Almudena Grandes y la periodista Pepa Bueno estar\u00e1n en el curso sobre \u2018Mujeres en el conocimiento\u2019"},"content":{"rendered":"<figure id=\"attachment_30857394\" aria-describedby=\"caption-attachment-30857394\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30857394\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k-750x500.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k-750x500.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k-360x240.jpg 360w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k-768x512.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k-600x400.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k-165x109.jpg 165w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k-1320x880.jpg 1320w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/07\/34728741335_7c2e05edd8_k.jpg 2048w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-30857394\" class=\"wp-caption-text\">Foto: Fundaci\u00f3n Cajasol<\/figcaption><\/figure>\n<p>Cuatro seminarios abren hoy la programaci\u00f3n de la <strong>segunda semana de la XVII edici\u00f3n de los Cursos de Verano de la Universidad Pablo de Olavide en Carmona<\/strong>. En ellos, se analizar\u00e1n tem\u00e1ticas actuales y diversas, como las mujeres en el conocimiento, la ciencia y la tecnolog\u00eda; el terrorismo yihadista, la sexualidad y el coaching t\u00e9cnico vocal.<\/p>\n<p>La secretaria de Estado de Universidades e I+D+i y presidenta del Observatorio Mujeres, Ciencia e Innovaci\u00f3n del Ministerio de Ciencia, Innovaci\u00f3n y Universidades, \u00c1ngeles Heras Caballero, ser\u00e1 la encargada de inaugurar el curso <strong>\u2018Mujeres en el conocimiento, la ciencia y la tecnolog\u00eda\u2019<\/strong> a partir de las 11 horas. Este curso, que se celebrar\u00e1 en la Casa Palacio de los Briones hasta el pr\u00f3ximo mi\u00e9rcoles, se estructura en torno a tres ejes esenciales para avanzar hacia una comprensi\u00f3n del mundo no androc\u00e9ntrica desde el conocimiento, la ciencia y la tecnolog\u00eda.<\/p>\n<p>Los estudios de mujeres, de g\u00e9nero y feministas han demostrado que un requisito indispensable para modificar la perspectiva de las mujeres en las instituciones, manifestaciones culturales, generaci\u00f3n de conocimiento y relatos, es que haya una presencia de mujeres lo suficientemente elevada para que las instituciones no cambien a las mujeres, sino que sean \u00e9stas las que cambien las instituciones. El seminario est\u00e1 dirigido por Adela Mu\u00f1oz P\u00e1ez, catedr\u00e1tica de Qu\u00edmica Inorg\u00e1nica de la Universidad de Sevilla y presidenta de AMIT Andaluc\u00eda y Blanca Rodr\u00edguez Ruiz, profesora titular de Derecho Constitucional de la Universidad de Sevilla.<\/p>\n<p>Tras la presentaci\u00f3n del curso, a las 12:00 horas, se celebrar\u00e1 la mesa redonda: \u2018Presencia y voces de mujeres\u2019, en la que participar\u00e1n la periodista Pepa Bueno, directora del programa \u2018Hoy por Hoy\u2019 de la Cadena SER, la escritora Almudena Grandes y la editora de Planeta \u00c1ngeles Aguilera. Dicha mesa ser\u00e1 moderada por Amparo Rubiales, presidenta del Consejo Social de la Universidad Pablo de Olavide.<\/p>\n<p>Por la tarde, el curso se retomar\u00e1 a las 16:00 horas con la mesa redonda: \u2018La lucha por la presencia y las vocaciones\u2019, de la que formar\u00e1n parte Silvia Marzal Romeu, ingeniera de dise\u00f1o de ciudades inteligentes de la Universidad Polit\u00e9cnica de Valencia; Carmen Vela, directora de Proyectos en Eurofins Ingenasa y ex secretaria de Estado de Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n (2012- 2019), adem\u00e1s de expresidenta de AMIT; Marta Macho, profesora de Geometr\u00eda y Topolog\u00eda de la Universidad del Pa\u00eds Vasco y responsable del blog &#8216;Mujeres con Ciencia&#8217;. Estar\u00e1 moderada por Clara Grima, profesora de Matem\u00e1tica Aplicada de la Universidad de Sevilla y presidenta de la Comisi\u00f3n de Divulgaci\u00f3n de la Real Sociedad Espa\u00f1ola de Matem\u00e1ticas. Por \u00faltimo, a las 18:30 horas tendr\u00e1 lugar la performance de la artista visual Yolanda Dom\u00ednguez, que ser\u00e1 presentada por Lydia Gil, responsable de la web de Cient\u00edficas Divulgadoras 30+30.<\/p>\n<p>Por otro lado, hoy tambi\u00e9n comienza en el Hotel Alc\u00e1zar de la Reina (C\/ Hermana Concepci\u00f3n Orellana, s\/n) <strong>el \u2018Curso internacional sobre terrorismo yihadista. 14\u00aa edici\u00f3n: potenciadores e inhibidores de la amenaza\u2019<\/strong>, dirigido por Manuel Ricardo Torres Soriano, profesor del Departamento de Derecho P\u00fablico de la Universidad Pablo de Olavide.<\/p>\n<p>En este seminario, que se extender\u00e1 hasta el mi\u00e9rcoles 3 de julio, pretende ofrecer una reflexi\u00f3n acad\u00e9mica y profesional sobre el fen\u00f3meno del terrorismo yihadista, aportando instrumentos de an\u00e1lisis desde diferentes enfoques cient\u00edficos y profesionales. Como continuaci\u00f3n y complemento a las 13 ediciones previas de esta actividad formativa, se dedica una especial atenci\u00f3n a las lecciones aprendidas acerca de cu\u00e1les son los factores que potencian la incidencia del terrorismo yihadista y de cu\u00e1les son las medidas que act\u00faan como inhibidores de esta amenaza.<\/p>\n<p>La jornada de hoy lunes comenzar\u00e1 a las 11 horas con la conferencia: \u201cEl impacto del cambio tecnol\u00f3gico en el activismo yihadista\u201d, que estar\u00e1 a cargo de Manuel Ricardo Torres Soriano. A continuaci\u00f3n, a las 12,00 horas, se abordar\u00e1 en una conferencia las \u2018Lecciones aprendidas de la campa\u00f1a militar contra el Daesh\u2019, que ofrecer\u00e1 Jos\u00e9 Luis Calvo-Albero, coronel del Ej\u00e9rcito de Tierra de la Secretar\u00eda General de Pol\u00edtica de Defensa. Mientras, la \u00faltima conferencia de la ma\u00f1ana se celebrar\u00e1 a las 13,00 horas y llevar\u00e1 por t\u00edtulo \u201cEvaluaci\u00f3n del riesgo de radicalizaci\u00f3n yihadista: desaf\u00edos y propuestas\u201d, que impartir\u00e1 el profesor Manuel Moyano Pacheco, del Departamento de Psicolog\u00eda de la Universidad de C\u00f3rdoba.<\/p>\n<p>La jornada de tarde de este curso arrancar\u00e1 a las 16,00 horas con la ponencia \u201cEvoluci\u00f3n del tratamiento medi\u00e1tico del yihadismo\u201d, que ofrecer\u00e1 Andr\u00e9s Ortiz Moyano, periodista especializado en comunicaci\u00f3n corporativa, relaciones internacionales, propaganda y yihadismo. Por \u00faltimo, a las 17 horas se celebrar\u00e1 la conferencia \u201cLa investigaci\u00f3n en temas sensibles: el terrorismo\u201d, que ser\u00e1 responsabilidad de Antonio M. D\u00edaz, profesor de Derecho Penal de la Universidad de C\u00e1diz.<\/p>\n<p>Otro de los cursos que se inauguran tambi\u00e9n hoy es<strong> \u2018Sexualidad (es) e intervenci\u00f3n socio-educativa\u2019<\/strong>, dirigido por el profesor Juan Blanco L\u00f3pez, del Departamento de Trabajo Social y Servicios Sociales de la Universidad Pablo de Olavide y que se celebrar\u00e1 en la Casa Palacio de los Briones hasta el 3 de julio.<\/p>\n<p>El objetivo de esta formaci\u00f3n es proporcionar un nuevo marco de comprensi\u00f3n a trav\u00e9s del cual el alumnado pueda dise\u00f1ar y desarrollar l\u00edneas de actuaci\u00f3n que faciliten el conocimiento, la aceptaci\u00f3n y la expresi\u00f3n de los peculiares modos de ser sexuados de las personas destinatarias de sus intervenciones sociales y educativas.<\/p>\n<p>El seminario comenzar\u00e1 a las 11 horas con la conferencia \u201cSexualidad(es) y ciudadan\u00eda: pivotando entre pr\u00e1cticas e identidades\u201d, que impartir\u00e1 el director del curso. A las 12 horas ser\u00e1 el turno de Marcos Sanz Ag\u00fcero, profesor de Sociolog\u00eda de la Sexualidad en los estudios de postgrado del Instituto de Sexolog\u00eda Incisex (Madrid), quien hablar\u00e1 sobre los \u201cViejos y nuevos desordenes amorosos: la moral sexual de nuestro tiempo\u201d. Para finalizar la jornada, a las 16:00 horas, se celebrar\u00e1 el taller \u201cLa construcci\u00f3n biogr\u00e1fica de la identidad sexuada y sus implicaciones en la intervenci\u00f3n social y educativa\u201d, que estar\u00e1 a cargo de Ignacio L\u00f3pez Mart\u00edn, socio fundador de Insex (Iniciativa Sexol\u00f3gica y Acci\u00f3n Social, Sociedad Cooperativa Andaluza de Inter\u00e9s Social).<\/p>\n<p>Por \u00faltimo, el lunes tambi\u00e9n se inaugura el curso \u2018Coaching t\u00e9cnico-vocal de alto rendimiento para audiciones, conciertos y giras. Formaci\u00f3n complementaria\u2019, que se desarrollar\u00e1 hasta el viernes 5 de julio en el Hotel Alc\u00e1zar de la Reina y que dirige e imparte Juana Castillo Ruz, soprano profesional.<\/p>\n<p>El curso consta de una serie de sesiones, que combinan el trabajo te\u00f3rico con el pr\u00e1ctico, sobre el desarrollo vocal espec\u00edfico para la mejora de los rendimientos en cantantes de todos los estilos en giras, audiciones y\/o concursos.<\/p>\n<p>El seminario comenzar\u00e1 a las 11 horas con la conferencia: \u201cEl instrumento vocal musical: su funcionamiento\u201d. A las 12:00 horas se celebrar\u00e1 el taller te\u00f3rico-pr\u00e1ctico: \u201cLa respiraci\u00f3n\u201d, mientras que a las 13:00 horas se realizar\u00e1 otro sobre \u201cAudici\u00f3n individual. 1\u00ba sondeo vocal\u201d. La jornada de tarde se iniciar\u00e1 a las 17,00 horas con el taller: \u201cImpostaci\u00f3n y emisi\u00f3n\u201d, mientras que a las 18 horas se ofrecer\u00e1 otro taller sobre audiciones y concursos, que llevar\u00e1 por t\u00edtulo \u201cDibujo del fraseo musical, tensi\u00f3n musical de la canci\u00f3n, din\u00e1mica f\u00edsica seg\u00fan estilo y canci\u00f3n, actitud psicoemocional, relaci\u00f3n sonido-cantante\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy lunes tambi\u00e9n comienzan otros seminarios sobre terrorismo yihadista, sexualidad e intervenci\u00f3n socio-educativa y coaching t\u00e9cnico vocal de alto rendimiento.<\/p>\n","protected":false},"author":6,"featured_media":30857394,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[729],"tags":[],"class_list":["post-30857393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-verano"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30857393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30857393"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30857393\/revisions"}],"predecessor-version":[{"id":30857396,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30857393\/revisions\/30857396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30857394"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30857393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30857393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30857393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}