{"id":30859176,"date":"2019-12-13T14:03:05","date_gmt":"2019-12-13T13:03:05","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30859176"},"modified":"2019-12-13T14:03:05","modified_gmt":"2019-12-13T13:03:05","slug":"cinco-estudiantes-de-la-upo-participan-este-sabado-en-el-cau-de-campo-a-traves-en-granada","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/comunidad\/2019\/12\/cinco-estudiantes-de-la-upo-participan-este-sabado-en-el-cau-de-campo-a-traves-en-granada\/","title":{"rendered":"Cinco estudiantes de la UPO participan este s\u00e1bado en el CAU de Campo a Trav\u00e9s en Granada"},"content":{"rendered":"<figure id=\"attachment_30859177\" aria-describedby=\"caption-attachment-30859177\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/12\/cau-campotraves2020.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30859177\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/12\/cau-campotraves2020-750x453.jpg\" alt=\"\" width=\"750\" height=\"453\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/12\/cau-campotraves2020-750x453.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/12\/cau-campotraves2020-360x218.jpg 360w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/12\/cau-campotraves2020-768x464.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/12\/cau-campotraves2020-600x363.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2019\/12\/cau-campotraves2020-1320x798.jpg 1320w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-30859177\" class=\"wp-caption-text\">Nuria Pacheco, M\u00f3nica Hern\u00e1ndez, Valme Prado y Pablo Gonz\u00e1lez competir\u00e1n este s\u00e1bado en Granada<\/figcaption><\/figure>\n<p>La Universidad Pablo de Olavide participar\u00e1 este s\u00e1bado, 14 de diciembre, en el <strong>Campeonato de Andaluc\u00eda Universitario (CAU) de Campo a Trav\u00e9s 2020<\/strong>, que se celebra en el Club N\u00e1utico de la Universidad de Granada, situado en el embalse de Cubillas. La UPO, que obtuvo en categor\u00eda femenina las \u00faltimas tres medallas de oro gracias a la memorable actuaci\u00f3n de M\u00f3nica Hern\u00e1ndez, estar\u00e1 representada por un total de cinco atletas, tres mujeres y dos hombres, en modalidad femenina y masculina.<\/p>\n<p>El equipo de la Universidad Pablo de Olavide estar\u00e1 formado en esta nueva edici\u00f3n por los atletas <strong>Pablo Gonz\u00e1lez P\u00e9rez, Jes\u00fas Mu\u00f1oz D\u00edaz, Nuria Pacheco Barbero, Valme Prado Dur\u00e1n<\/strong> y la tres veces medalla de oro, <strong>M\u00f3nica Hern\u00e1ndez<\/strong>. La joven atleta es una de las voces m\u00e1s autorizadas para hablar de estos campeonatos debido a su experiencia y palmar\u00e9s. M\u00f3nica, que disputar\u00e1 su quinto y \u00faltimo CAU, asegura que la UPO puede \u201caspirar a este t\u00edtulo un a\u00f1o m\u00e1s\u201d sin ning\u00fan problema.<\/p>\n<p>La tricampeona espera poner el \u201cbroche\u201d a su etapa universitaria en el \u00e1mbito deportivo, ya que este ser\u00e1 su \u00faltimo a\u00f1o compitiendo en los campeonatos universitarios porque se desvincular\u00e1 de la comunidad universitaria una vez haya finalizado el m\u00e1ster que est\u00e1 realizando en la Universidad Pablo de Olavide. Asimismo, a\u00f1ade que \u201cme gustar\u00eda cerrar esta etapa de la mejor manera posible\u201d y que no \u201cborrar\u00eda ning\u00fan momento amargo\u201d, puesto que el atletismo le ha convertido en quien es actualmente.<\/p>\n<p>Por otro lado, esta nueva edici\u00f3n arrancar\u00e1 con la carrera femenina a las 12,30 horas y ser\u00e1 de 6.000 metros (cuatro vueltas al circuito), mientras que la masculina, que se desarrollar\u00e1 a las 13,15 horas, ser\u00e1 de 7.500 metros (cinco vueltas al circuito). Asimismo, a las 11,30 horas se realizar\u00e1 el reconocimiento del circuito (1.450 m.) y la entrega de premios tendr\u00e1 lugar a las 14,15 horas.<\/p>\n<p>Como en ediciones anteriores, en esta modalidad se establecer\u00e1n dos clasificaciones: una individual y otra por universidades, tanto de categor\u00eda masculina como femenina. Las primeras ser\u00e1n de acuerdo con el orden de llegada a meta, mientras que las segundas se obtendr\u00e1n sumando los puntos obtenidos por los tres corredores mejor clasificados del equipo masculino y por las dos corredoras mejor clasificadas del equipo femenino.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Pablo de Olavide participar\u00e1 este s\u00e1bado, 14 de diciembre, en el Campeonato de Andaluc\u00eda Universitario (CAU) de Campo a Trav\u00e9s 2020, que se celebra en el Club N\u00e1utico de la Universidad de Granada, situado en el embalse de Cubillas. La UPO, que obtuvo en categor\u00eda femenina las \u00faltimas tres medallas de oro gracias a la memorable actuaci\u00f3n de M\u00f3nica Hern\u00e1ndez, estar\u00e1 representada por un total de cinco atletas, tres mujeres y dos hombres, en modalidad femenina y masculina. <\/p>\n","protected":false},"author":6,"featured_media":30859177,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5842],"tags":[190,1209,255,324,1310,541,21,39],"class_list":["post-30859176","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","tag-andalucia","tag-campeonato-andalucia-universitario","tag-campo-a-traves","tag-cau","tag-competicion","tag-deporte","tag-estudiantes","tag-universidades"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30859176","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30859176"}],"version-history":[{"count":1,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30859176\/revisions"}],"predecessor-version":[{"id":30859178,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30859176\/revisions\/30859178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30859177"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30859176"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30859176"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30859176"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}