{"id":30861660,"date":"2020-09-16T11:03:59","date_gmt":"2020-09-16T09:03:59","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30861660"},"modified":"2020-09-18T16:57:39","modified_gmt":"2020-09-18T14:57:39","slug":"proponen-un-propocolo-para-evaluar-el-impacto-del-covid-19-sobre-la-salud-comunitaria","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/ciencia\/2020\/09\/proponen-un-propocolo-para-evaluar-el-impacto-del-covid-19-sobre-la-salud-comunitaria\/","title":{"rendered":"Proponen un protocolo para evaluar el impacto del Covid-19 sobre la salud comunitaria"},"content":{"rendered":"<figure id=\"attachment_936874\" aria-describedby=\"caption-attachment-936874\" style=\"width: 320px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-936874\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/05\/avillar1-320x213.jpg\" alt=\"Antonio Villar es catedr\u00e1tico de Fundamentos de An\u00e1lisis Econ\u00f3mico de la UPO\" width=\"320\" height=\"213\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/05\/avillar1-320x213.jpg 320w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/05\/avillar1-1024x682.jpg 1024w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2013\/05\/avillar1-600x400.jpg 600w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-936874\" class=\"wp-caption-text\">Antonio Villar es catedr\u00e1tico de Fundamentos de An\u00e1lisis Econ\u00f3mico de la UPO<\/figcaption><\/figure>\n<p>El catedr\u00e1tico de An\u00e1lisis Econ\u00f3mico de la Universidad Pablo de Olavide <strong>Antonio Villar<\/strong> junto con catedr\u00e1tica de Fundamentos del An\u00e1lisis Econ\u00f3mico de la Universidad de Alicante <strong>Carmen Herrero<\/strong>, han realizado un estudio en el que proponen un <strong>protocolo para evaluar el impacto del COVID-19 sobre la salud comunitaria.<\/strong><\/p>\n<p>La prestigiosa <strong>revista cient\u00edfica <em>Plos One<\/em><\/strong> ha publicado dicha investigaci\u00f3n bajo el nombre \u2018<em><a href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0238970\">A synthetic indicator on the impact of COVID-19 on the community\u2019s health<\/a><\/em>\u2019, en el que los investigadores desarrollan un protocolo que combina la medici\u00f3n de la <strong>incidencia<\/strong> del COVID-19 con una estimaci\u00f3n de la <strong>severidad<\/strong>, en l\u00ednea con las recomendaciones de las agencias internacionales.<\/p>\n<p>\u201cLa r\u00e1pida transmisi\u00f3n del COVID-19 en todo el mundo ha obligado a los gobiernos a tomar medidas dr\u00e1sticas para contener el contagio y ha supuesto un enorme estr\u00e9s para los sistemas sanitarios a la hora de poder atender a los afectados de mayor gravedad\u201d, explican los investigadores.<\/p>\n<p>Por ello, para tener una idea clara de la evoluci\u00f3n de la pandemia y de la efectividad de las medidas adoptadas conviene monitorizar de forma sistem\u00e1tica tanto la evoluci\u00f3n del n\u00famero de infectados como la severidad de los que sufren el contagio. \u201cLas diferencias entre las cifras de contagio y de hospitalizaciones de este verano con respecto a las de la pasada primavera ilustran bien la necesidad de prestar atenci\u00f3n a ambos factores: la <strong>incidencia<\/strong> de la enfermedad y su <strong>intensidad\u201d, <\/strong>sostienen los investigadores del estudio. Esta idea figura en los protocolos de seguimiento de las principales agencias de salud internacionales como la Organizaci\u00f3n Mundial de la Salud, el Departamento de Salud de Estados Unidos, o el Centro Europeo para la Prevenci\u00f3n y Control de Enfermedades (v.g. el <em>Pandemic Influenza Severity Assessment<\/em> de la OMS, o el <em>Pandemic Severity Assessment Framework<\/em> en Estados Unidos).<\/p>\n<figure id=\"attachment_30861662\" aria-describedby=\"caption-attachment-30861662\" style=\"width: 360px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30861662\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-360x237.jpg\" alt=\"\" width=\"360\" height=\"237\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-360x237.jpg 360w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-750x494.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-768x506.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-600x395.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-380x250.jpg 380w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-760x500.jpg 760w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1-165x109.jpg 165w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2020\/09\/impacto_covid19_gr\u00e1fico-1.jpg 1126w\" sizes=\"auto, (max-width: 360px) 100vw, 360px\" \/><figcaption id=\"caption-attachment-30861662\" class=\"wp-caption-text\">Distribuci\u00f3n de estados de salud por los afectados del Covid-19 en las regiones italianas el d\u00eda 8 de Abril de 2020.<\/figcaption><\/figure>\n<h3><strong>Metodolog\u00eda empleada<\/strong><\/h3>\n<p>El <strong>\u00edndice de impacto del COVID-19<\/strong> viene dado por el <strong>producto de la incidencia y una medida de severidad<\/strong>. \u201cEs decir, cu\u00e1ntos contagiados hay, en t\u00e9rminos relativos, por cu\u00e1l es su estado de gravedad. Nos ofrece una medida del grado en que cada comunidad se ve afectada por la enfermedad, resultante de la tensi\u00f3n sanitaria y la amplitud del problema\u201d, explica Antonio Villar.<\/p>\n<p>Para medir la severidad se utilizan los datos sobre la distribuci\u00f3n de la poblaci\u00f3n afectada en distintos estados de salud (curados, asintom\u00e1ticos o con s\u00edntomas leves, aislados en casa, hospitalizados en planta, hospitalizados en cuidados intensivos y fallecidos). La valoraci\u00f3n de estas distribuciones se realiza mediante una estimaci\u00f3n de la probabilidad relativa de que un individuo afectado se encuentre en mejor estado de salud, al comparar dos momentos del tiempo o varias sociedades. Este tipo de comparaci\u00f3n permite, merced a una metodolog\u00eda desarrollada por los propios autores, obtener un indicador de severidad mediante el que estimar la evoluci\u00f3n temporal de la pandemia o la situaci\u00f3n relativa de diferentes pa\u00edses o regiones.<\/p>\n<p>Al no poder emplear datos de la evoluci\u00f3n de la pandemia en Espa\u00f1a por los continuos bailes de cifras y cambios de criterio en el recuento de casos, los investigadores ilustraron la metodolog\u00eda mediante <strong>el an\u00e1lisis de la situaci\u00f3n de las regiones italianas<\/strong> en dos momentos del tiempo, el d\u00eda 9 de marzo de 2020, cuando empez\u00f3 el confinamiento, y un mes despu\u00e9s. En dicho periodo el impacto en todo el pa\u00eds se multiplic\u00f3 por 10, mientras que en algunas regiones se multiplic\u00f3 por m\u00e1s de 40. Los mayores crecimientos se produjeron en las regiones con valores iniciales inferiores, de modo que la diversidad extrema entre las regiones italianas se redujo sustancialmente, lo que indica que el confinamiento ha resultado una pol\u00edtica eficaz para combatir la enfermedad. La severidad disminuy\u00f3 fuertemente en la mayor\u00eda de las regiones, con una reducci\u00f3n general del 33%. Esta reducci\u00f3n se produjo con mayor intensidad en aquellas regiones con peores indicadores iniciales, lo que sugiere que el sistema de salud respondi\u00f3 correctamente y lo hizo con mayor intensidad en aquellas regiones m\u00e1s necesitadas.<\/p>\n<p>\u201cDesgraciadamente, la mala calidad de los datos espa\u00f1oles y los continuos cambios de criterio no han permitido llevar a cabo un an\u00e1lisis similar en el caso espa\u00f1ol, aunque en su momento lo intentamos\u201d, declaran los autores de la investigaci\u00f3n, quienes obtuvieron los datos de las regiones italianas de la <a href=\"http:\/\/opendatadpc.maps.arcgis.com\/apps\/opsdashboard\/index.html#\/b0c68bce2cce478eaac82fe38d4138b1\">p\u00e1gina web del Ministerio de Salud<\/a> de este pa\u00eds, web que ofrec\u00eda datos diarios, homog\u00e9neos y p\u00fablicos.<\/p>\n<h3><strong><u>Referencia del art\u00edculo<\/u><\/strong>:<\/h3>\n<p>Herrero C, Villar A (2020) <strong><em>A synthetic indicator on the impact of COVID-19 on the community\u2019s health<\/em><\/strong>. PLoS ONE 15(9): e0238970. <a href=\"https:\/\/doi.org\/10.1371\/journal.pone.0238970\">https:\/\/doi.org\/10.1371\/journal.pone.0238970<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El catedr\u00e1tico de An\u00e1lisis Econ\u00f3mico de la Universidad Pablo de Olavide Antonio Villar junto con catedr\u00e1tica de Fundamentos del An\u00e1lisis Econ\u00f3mico de la Universidad de Alicante Carmen Herrero, han realizado un estudio en el que proponen un protocolo para evaluar el impacto del COVID-19 sobre la salud comunitaria.<\/p>\n","protected":false},"author":2,"featured_media":30861662,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3],"tags":[576,6601,6890,6516,6891,5978,6889],"class_list":["post-30861660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","tag-antonio-villar","tag-covid-19","tag-incidencia","tag-indicadores","tag-indice","tag-protocolo","tag-salud-comunitaria"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30861660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30861660"}],"version-history":[{"count":3,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30861660\/revisions"}],"predecessor-version":[{"id":30861665,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30861660\/revisions\/30861665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30861662"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30861660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30861660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30861660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}