{"id":30867460,"date":"2021-07-07T07:21:24","date_gmt":"2021-07-07T05:21:24","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30867460"},"modified":"2021-07-08T17:25:16","modified_gmt":"2021-07-08T15:25:16","slug":"cosette-franco-lamenta-que-la-crisis-de-valores-de-la-sociedad-lleva-a-terribles-desenlaces","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/cursos-verano\/2021\/07\/cosette-franco-lamenta-que-la-crisis-de-valores-de-la-sociedad-lleva-a-terribles-desenlaces\/","title":{"rendered":"Cosette Franco lamenta que la \u00abcrisis de valores de la sociedad\u00bb lleva a \u00abterribles desenlaces\u00bb"},"content":{"rendered":"<figure id=\"attachment_30867463\" aria-describedby=\"caption-attachment-30867463\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/07\/cosette-web.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30867463\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/07\/cosette-web-750x409.jpg\" alt=\"Cosette Franco\" width=\"750\" height=\"409\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/07\/cosette-web-750x409.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/07\/cosette-web-360x196.jpg 360w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/07\/cosette-web-768x419.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/07\/cosette-web-600x327.jpg 600w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2021\/07\/cosette-web.jpg 1100w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-30867463\" class=\"wp-caption-text\">Cosette Franco<\/figcaption><\/figure>\n<p>Franco ha hecho estas declaraciones en relaci\u00f3n al fallecimiento de Samuel en La Coru\u00f1a tras recibir una agresi\u00f3n mortal. \u00abHoy d\u00eda seguimos escuchando argumentos que justifican de manera absurda y repudiable el uso de la violencia\u00bb, ha indicado en una entrevista.<\/p>\n<p>La antrop\u00f3loga dirige el <strong>curso \u2018Intervenci\u00f3n social con personas en riesgo de exclusi\u00f3n\u2019<\/strong>, en el marco de la XIX edici\u00f3n de los Cursos de Verano de la Universidad Pablo de Olavide (UPO) en Carmona (Sevilla).<\/p>\n<p><strong>Franco se ha referido a la exclusi\u00f3n social como \u00abun fen\u00f3meno que puede afectar a cualquier persona\u00bb<\/strong> y ha precisado que \u00ablos estudios tradicionales vinculaban la exclusi\u00f3n a zonas con necesidades de transformaci\u00f3n social y, sin embargo, los \u00faltimos acontecimientos hist\u00f3ricos como la crisis econ\u00f3mica o la actual pandemia mundial hacen extensivo este riesgo a colectivos aparentemente exentos de peligro de vulnerabilidad social\u00bb.<\/p>\n<p>La directora del curso ha aportado datos de la Plataforma Europea de Entidades Sociales que trabajan y luchan contra la pobreza y la exclusi\u00f3n social (EANP):<strong> el 37,7 % de la poblaci\u00f3n de Andaluc\u00eda est\u00e1 en riesgo de pobreza y\/o exclusi\u00f3n social en el a\u00f1o 2019.<\/strong> En t\u00e9rminos absolutos, \u00abalgo menos de 3,2 millones de personas residentes en Andaluc\u00eda\u00bb. De ellos, casi el 17% est\u00e1 dentro del marco de pobreza severa, es decir, tiene unos ingresos por debajo de los 500 euros mensuales por unidad de consumo.<\/p>\n<p>Respecto a las principales causas que derivan en la exclusi\u00f3n social, Franco ha indicado que <strong>\u00abvivimos en una sociedad excluyente, donde prevalece la desigualdad social justificado por el modelo capitalista que rige nuestra econom\u00eda\u00bb<\/strong>.<\/p>\n<p>Sobre esto, ha a\u00f1adido que \u00ablas personas en situaci\u00f3n de riesgo social han llegado a esta situaci\u00f3n por una serie de casu\u00edsticas vinculadas con alguno o varios de los siguientes factores: p\u00e9rdida de empleo, escasos o nulos ingresos econ\u00f3micos, falta de redes sociales y familiares de apoyo, consumo de sustancias t\u00f3xicas y, en algunos casos, situaciones de migraci\u00f3n o pertenencia a culturas minoritarias\u00bb.<\/p>\n<p>Respecto a los riesgos que padecen los menores en riesgo de exclusi\u00f3n social, ha manifestado que \u00abun menor en riesgo social es susceptible de ver mermadas sus capacidades de maduraci\u00f3n f\u00edsica, psicol\u00f3gica, afectiva y relacional con graves secuelas para su futuro\u00bb.<\/p>\n<p>Preguntada por la crisis migratoria, Franco ha argumentado que \u00abexiste una tendencia a invisibilizar la situaci\u00f3n de vulnerabilidad que viven y padecen millones de familias\u00bb, ya que \u00ablas denominadas crisis de la migraci\u00f3n o incluso el t\u00e9rmino MENA no hace m\u00e1s que nombrar con acr\u00f3nimos a personas que quieren ejercer su derecho a lo que desde la Constituci\u00f3n Espa\u00f1ola en su art\u00edculo 15 se recoge como derecho a la vida y a la integridad f\u00edsica y moral\u00bb.<\/p>\n<p>En esta l\u00ednea, ha indicado que, \u00aba pesar de su reconocimiento formal sigue, desgraciadamente, ampli\u00e1ndose la distancia entre la legislaci\u00f3n y la realidad, como los casos de Ceuta, donde a trav\u00e9s de la manipulaci\u00f3n pol\u00edtica se utiliza la vulnerabilidad de estas personas o en el caso de propaganda y campa\u00f1as de desinformaci\u00f3n contra menores no acompa\u00f1ados lo que no hacen m\u00e1s que provocar una reacci\u00f3n absolutamente injusta y provocadora del continuo rechazo a determinados colectivos\u00bb.<\/p>\n<p>Respecto a los nuevos modelos de exclusi\u00f3n social, la presidenta de la Asociaci\u00f3n Ariadna ha subrayado que \u00abexisten nuevas formas de vulnerabilidad en la que miles de familias se encuentran en riesgo, como las conductas disruptivas en las que incurren muchos de los j\u00f3venes de nuestra sociedad en distintos \u00e1mbitos como problemas de convivencia en centros educativos, violencia de g\u00e9nero entre parejas cada vez m\u00e1s j\u00f3venes o las recientes violaciones en grupo a trav\u00e9s de las denominadas manadas\u00bb.<\/p>\n<p>Tambi\u00e9n ha recalcado que \u00abotra de estas conductas en auge es la recientemente catalogada como problema social, la violencia filioparental\u00bb.<\/p>\n<p>Por \u00faltimo, Franco ha resaltado que \u00ablas pol\u00edticas de empleo, econ\u00f3micas y de protecci\u00f3n social son insuficientes\u00bb y ha abogado \u00abcompaginarlas con estrategias educativas que hagan posible una transformaci\u00f3n ideol\u00f3gica y real, medidas a largo plazo a trav\u00e9s de metodolog\u00edas innovadoras y con continuidad en su desarrollo\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Franco ha hecho estas declaraciones en relaci\u00f3n al fallecimiento de Samuel en La Coru\u00f1a tras recibir una agresi\u00f3n mortal. \u00abHoy d\u00eda seguimos escuchando argumentos que justifican de manera absurda y repudiable el uso de la violencia\u00bb, ha indicado en una entrevista.<\/p>\n","protected":false},"author":6,"featured_media":30867463,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[729],"tags":[23,22,455],"class_list":["post-30867460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-verano","tag-carmona","tag-cursos-de-verano","tag-exclusion-social"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30867460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30867460"}],"version-history":[{"count":3,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30867460\/revisions"}],"predecessor-version":[{"id":30867464,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30867460\/revisions\/30867464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30867463"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30867460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30867460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30867460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}