{"id":30873938,"date":"2022-06-30T08:29:32","date_gmt":"2022-06-30T06:29:32","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30873938"},"modified":"2022-06-30T14:35:29","modified_gmt":"2022-06-30T12:35:29","slug":"comienza-el-curso-la-segunda-oportunidad-segun-el-trlc-y-viabilidad-y-reestructuracion-societaria","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/cursos-verano\/2022\/06\/comienza-el-curso-la-segunda-oportunidad-segun-el-trlc-y-viabilidad-y-reestructuracion-societaria\/","title":{"rendered":"Comienza el curso \u2018La segunda oportunidad seg\u00fan el TRLC y viabilidad y reestructuraci\u00f3n societaria\u2019"},"content":{"rendered":"<figure id=\"attachment_30873939\" aria-describedby=\"caption-attachment-30873939\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-30873939 size-large\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled-e1656592498512-750x396.jpg\" alt=\"Desde la izquierda:  Ismael Cay\u00f3n, abogado; Cecilia Franco, directora del curso y Virginia Jim\u00e9nez, abogada, en la inauguraci\u00f3n del seminario\" width=\"750\" height=\"396\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled-e1656592498512-750x396.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled-e1656592498512-385x203.jpg 385w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled-e1656592498512-768x405.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled-e1656592498512-1536x811.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled-e1656592498512-2048x1081.jpg 2048w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2022\/06\/CuVe-Segunda-oportunidad-scaled-e1656592498512-1320x697.jpg 1320w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-30873939\" class=\"wp-caption-text\">Desde la izquierda: Ismael Cay\u00f3n, abogado; Cecilia Franco, directora del curso y Virginia Jim\u00e9nez, abogada<\/figcaption><\/figure>\n<p>La sede Olavide en Carmona acoge desde hoy y hasta el viernes el curso de verano<strong> \u2018La segunda oportunidad seg\u00fan el TRLC y viabilidad y reestructuraci\u00f3n societaria\u2019<\/strong>, que se celebra dentro de la 20 edici\u00f3n de los cursos de verano. Este seminario, que se celebra en modalidad dual, est\u00e1 dirigido por Jos\u00e9 Mar\u00eda Ortega Segura y Cecilia Franco Romero, abogados socios de Iureko Abogados y Economistas.<\/p>\n<p>La trasposici\u00f3n de la directiva de insolvencia y la nueva regulaci\u00f3n de la segunda oportunidad hacen necesario un curso especializado y meramente pr\u00e1ctico para aquellos que se dedican a este trabajo o de aquellos que quieran empezar en este mundo.<\/p>\n<h3><strong>Temas y ponentes<\/strong><\/h3>\n<p>Entre los temas que se abordar\u00e1n en este seminario figuran las sociedades fantasma en los estados miembros; la nueva figura del experto en reestructuraci\u00f3n; los acuerdos de refinanciaci\u00f3n, impugnaciones y falta de cumplimiento; la transposici\u00f3n de la directiva de insolvencia o las cuestiones pr\u00e1cticas sobre las alertas tempranas.<\/p>\n<p>Son numerosos los expertos que participan en este curso, entre los que podemos citar al profesor \u00c1ngel Mar\u00eda Ballesteros Barros, de la Universidad de C\u00e1diz; Jos\u00e9 Moya Yoldi, socio de Cuatrecasas; los economistas Juan Carlos Mor\u00e1n \u00c1lvarez y Mercedes Nilo Mart\u00ednez Piller o los magistrados Pedro M\u00e1rquez Rubio, Eduardo G\u00f3mez L\u00f3pez, Javier Carretero Espinosa de los Monteros y Juan Santana, entre otros profesionales.<\/p>\n<p>Para consultar el programa completo del curso: <a href=\"https:\/\/www.upo.es\/formacionpermanente\/cursos-de-verano\/la-segunda-oportunidad-segun-el-trlc-y-viabilidad-y-reestructuracion-societaria\/\">PROGRAMA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Este seminario, que se impartir\u00e1 en modalidad dual, abordar\u00e1 la trasposici\u00f3n de la directiva de insolvencia y la nueva regulaci\u00f3n de la segunda oportunidad.<\/p>\n","protected":false},"author":6,"featured_media":30873939,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[729],"tags":[23,22,63,1059,874,519],"class_list":["post-30873938","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-verano","tag-carmona","tag-cursos-de-verano","tag-economia","tag-empresas","tag-financiacion","tag-olavide-en-carmona"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30873938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30873938"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30873938\/revisions"}],"predecessor-version":[{"id":30873941,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30873938\/revisions\/30873941"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30873939"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30873938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30873938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30873938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}