{"id":30879245,"date":"2023-07-10T13:16:53","date_gmt":"2023-07-10T11:16:53","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30879245"},"modified":"2023-09-11T10:04:41","modified_gmt":"2023-09-11T08:04:41","slug":"casi-500-estudiantes-de-la-provincia-de-sevilla-se-examinan-de-la-pevau-extraordinaria-en-la-upo","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/institucional\/2023\/07\/casi-500-estudiantes-de-la-provincia-de-sevilla-se-examinan-de-la-pevau-extraordinaria-en-la-upo\/","title":{"rendered":"Casi 500 estudiantes de la provincia de Sevilla se examinan de la PEvAU Extraordinaria en la UPO"},"content":{"rendered":"<p><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/07\/PEvAU-UPO-21-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30879246\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/07\/PEvAU-UPO-21-750x422.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/07\/PEvAU-UPO-21-750x422.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/07\/PEvAU-UPO-21-420x236.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/07\/PEvAU-UPO-21-768x432.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/07\/PEvAU-UPO-21-1536x864.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/07\/PEvAU-UPO-21-2048x1152.jpg 2048w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>Un total de <strong>482 estudiantes, 325 mujeres (67,42%) y 157 hombres (32,57%), procedentes de 35 centros de Sevilla capital y provincia<\/strong> se examinar\u00e1n en la convocatoria extraordinaria de la <strong>Prueba de Evaluaci\u00f3n y Acceso a la Universidad (PEvAU)<\/strong> en el campus de la Universidad Pablo de Olavide entre el martes 11 y el jueves 13 de julio. Las calificaciones se publicar\u00e1n en los portales web de la Universidad el mi\u00e9rcoles 19 de julio.<\/p>\n<p>En la convocatoria extraordinaria de este a\u00f1o, se han inscrito 206 estudiantes que realizar\u00e1n en la UPO la fase de acceso junto a la de admisi\u00f3n; 246 solamente har\u00e1n los ex\u00e1menes de admisi\u00f3n, al tener superada la de acceso; y 30 estudiantes se han inscrito \u00fanicamente para esta \u00faltima.<\/p>\n<p>Para el desarrollo de las pruebas, la UPO ha dispuesto <strong>una \u00fanica sede en el Edificio 4 de su campus y ser\u00e1 en el Edificio 6 donde se examinar\u00e1 el alumnado con necesidades educativas especiales<\/strong>.<\/p>\n<p>La prueba, para la que se mantiene el modelo dise\u00f1ado a ra\u00edz de la pandemia de Covid-19, comienza el martes 11 con tres de los cuatro ex\u00e1menes de la Fase de Acceso, que es obligatoria: Lengua Castellana y Literatura, Historia de Espa\u00f1a y Lengua Extranjera. El mi\u00e9rcoles contin\u00faa la prueba con el examen de la materia troncal general seg\u00fan la modalidad de segundo de Bachillerato elegida entre Fundamentos del Arte II, Lat\u00edn II, Matem\u00e1ticas II y Matem\u00e1ticas Aplicadas a las Ciencias Sociales. El jueves concluye la prueba con el resto de materias.<\/p>\n<p>El proceso de preinscripci\u00f3n, donde se realizar\u00e1 la solicitud de plazas en las Universidades P\u00fablicas Andaluzas, comprende entre el 19 y el 21 de julio. Todo ello de forma telem\u00e1tica a trav\u00e9s de la p\u00e1gina del <a href=\"https:\/\/www.juntadeandalucia.es\/economiaconocimientoempresasyuniversidad\/sguit\/\">Distrito \u00danico Andaluz<\/a>. Para m\u00e1s informaci\u00f3n, la UPO pone a disposici\u00f3n de los y las estudiantes <a href=\"https:\/\/www.upo.es\/estudiantes\/es\/index.html\">iPuntOlavide<\/a>, un nuevo portal de informaci\u00f3n donde encontrar orientaci\u00f3n sobre estos procesos en la secci\u00f3n <a href=\"https:\/\/www.upo.es\/estudiantes\/es\/futuros-estudiantes\/\">Antes del Grado<\/a>.<\/p>\n<p>En la sede de la Universidad Pablo de Olavide se examinar\u00e1n estudiantes del Centro de Estudios Sanitarios Dr. Ardu\u00e1n, CDP Sagrada Familia \u2013 Nuestra Se\u00f1ora de los Reyes, IES Carmen Laff\u00f3n, IES Joaqu\u00edn Turina, IES Juan de Mairena, IES Palomares, IES Sotero Hern\u00e1ndez e IES Vel\u00e1zquez, CDP Ergos, CDP Ergos Anidi, CDP Salesianos San Pedro, CDP San Fernando, IES Atenea, IES Chaves Nogales, IES Ruiz Gij\u00f3n, IES Severo Ochoa, CDP Centro de Estudios Superiores Aljarafe, CDP Saint Mary\u00b4s School, IES El Molinillo, IES Los \u00c1lamos, IES Mar\u00eda Galiana, IES Mateo Alem\u00e1n, IES Miguel de Cervantes, IES Ram\u00f3n del Valle Incl\u00e1n, CDP Albaydar, CDP Alberto Durero, CDP Antonio de Sol\u00eds, CDP CEFOA, CDP CESUR CAFD, CDP Instituto T\u00e9cnico Pablo de la Torre, CDP Las Artes, IES Camas, IES Mariana Pineda, IES Pepe Ruiz Vela e IES Rodrigo Caro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un total de 482 estudiantes, 325 mujeres (67,42%) y 157 hombres (32,57%), procedentes de 35 centros de Sevilla capital y provincia se examinar\u00e1n en la convocatoria extraordinaria de la Prueba de Evaluaci\u00f3n y Acceso a la Universidad (PEvAU) en el campus de la Universidad Pablo de Olavide entre el martes 11 y el jueves 13 de julio. Las calificaciones se publicar\u00e1n en los portales web de la Universidad el mi\u00e9rcoles 19 de julio.<\/p>\n","protected":false},"author":14,"featured_media":30879246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[1462,717,21,7529,39,2114],"class_list":["post-30879245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-institucional","tag-acceso-a-la-universidad","tag-distrito-unico-andaluz","tag-estudiantes","tag-pevau-extraordinaria","tag-universidades","tag-vicerrectorado-de-estudiantes"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30879245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30879245"}],"version-history":[{"count":3,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30879245\/revisions"}],"predecessor-version":[{"id":30879249,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30879245\/revisions\/30879249"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30879246"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30879245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30879245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30879245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}