{"id":30883165,"date":"2024-07-13T07:00:56","date_gmt":"2024-07-13T05:00:56","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30883165"},"modified":"2024-07-12T15:40:57","modified_gmt":"2024-07-12T13:40:57","slug":"practicas-arqueologicas-en-las-termas-romanas-de-carmona-en-los-cursos-de-verano-de-la-upo","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/cursos-verano\/2024\/07\/practicas-arqueologicas-en-las-termas-romanas-de-carmona-en-los-cursos-de-verano-de-la-upo\/","title":{"rendered":"Pr\u00e1cticas arqueol\u00f3gicas en las termas romanas de Carmona, en los Cursos de Verano de la UPO"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-30880316\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/11\/cursos-de-verano-cabecera-web-1-1024x189-1-750x138.png\" alt=\"Cursos de Verano\" width=\"750\" height=\"138\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/11\/cursos-de-verano-cabecera-web-1-1024x189-1-750x138.png 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/11\/cursos-de-verano-cabecera-web-1-1024x189-1-420x78.png 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/11\/cursos-de-verano-cabecera-web-1-1024x189-1-768x142.png 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2023\/11\/cursos-de-verano-cabecera-web-1-1024x189-1.png 1024w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/>Tres seminarios abrir\u00e1n el pr\u00f3ximo lunes 15 de julio la programaci\u00f3n de la quinta semana de la XXII edici\u00f3n de los Cursos de Verano de la Universidad Pablo de Olavide en Carmona. Ser\u00e1n los cursos \u2018Arqueolog\u00eda de campo. 17\u00aa edici\u00f3n\u2019, \u2018Coaching vocal de alto rendimiento: preparaci\u00f3n t\u00e9cnico-vocal de audiciones, concursos y giras. 5\u00aa edici\u00f3n\u2019 y \u2018Marketing cultural y art\u00edstico\u2019. Los tres se realizar\u00e1n de forma presencial.<\/p>\n<p>Este lunes, la jornada dar\u00e1 comienzo con el <strong>curso \u2018Arqueolog\u00eda de campo. 17\u00aa edici\u00f3n\u2019<\/strong>, que se celebrar\u00e1 hasta el pr\u00f3ximo 26 de julio. Un seminario dirigido por <strong>Ricardo Lineros<\/strong>, jefe de Servicio de la Delegaci\u00f3n de Patrimonio Hist\u00f3rico del Ayuntamiento de Carmona y Juan Manuel Rom\u00e1n, arque\u00f3logo municipal de dicha Delegaci\u00f3n. Los alumnos participar\u00e1n en una excavaci\u00f3n arqueol\u00f3gica preventiva, concretamente en las termas romanas de Carmona, y practicar\u00e1n todas las t\u00e9cnicas que se desarrollan en una intervenci\u00f3n de este tipo. Las pr\u00e1cticas de campo se apoyar\u00e1n en sesiones te\u00f3ricas sobre metodolog\u00eda arqueol\u00f3gica.<\/p>\n<p>Tambi\u00e9n se inaugura este lunes, el <strong>curso \u2018Coaching vocal de alto rendimiento: preparaci\u00f3n t\u00e9cnico-vocal de audiciones, concursos y giras. 5\u00aa edici\u00f3n\u2019<\/strong>, dirigido por <strong>Juana Castillo Ruz<\/strong>, soprano profesional y profesora t\u00e9cnico vocal. El curso, que se extender\u00e1 hasta el viernes 19 de julio, consta de una serie de sesiones que combinan el trabajo te\u00f3rico con el pr\u00e1ctico, sobre el desarrollo vocal espec\u00edfico para la mejora de los rendimientos en cantantes de todos los estilos en giras, audiciones y\/o concursos.<\/p>\n<p>El \u00faltimo de los cursos que se inicia el lunes y hasta el pr\u00f3ximo mi\u00e9rcoles 17 de julio es <strong>\u2018Marketing cultural y art\u00edstico\u2019<\/strong>, cuya directora y docente es <strong>Carmen Ana Vicente Ruiz<\/strong>, gestora cultural freelance. A trav\u00e9s de este curso, el alumnado tendr\u00e1 la posibilidad de adentrarse en casos reales a trav\u00e9s de los cuales descubrir\u00e1n nuevas formas de marketing adaptadas a proyectos culturales y art\u00edsticos.<\/p>\n<p>Para consultar los <strong>programas de los cursos:<\/strong><\/p>\n<ul>\n<li>\u2018<a href=\"https:\/\/www.upo.es\/formacionpermanente\/cursos-de-verano\/arqueologia-de-campo\/\">Arqueolog\u00eda de campo. 17\u00aa edici\u00f3n\u2019 (15 al 26 de julio)<\/a><\/li>\n<li>\u2018<a href=\"https:\/\/www.upo.es\/formacionpermanente\/cursos-de-verano\/coaching-vocal-de-alto-rendimiento-preparacion-tecnico-vocal-de-audiciones-concursos-y-giras\/\">Coaching vocal de alto rendimiento: preparaci\u00f3n t\u00e9cnico-vocal de audiciones, concursos y giras. 5\u00aa edici\u00f3n\u2019. (15 al 19 de julio)<\/a><\/li>\n<li>\u2018<a href=\"https:\/\/www.upo.es\/formacionpermanente\/cursos-de-verano\/marketing-cultural-y-artistico\/\">Marketing cultural y art\u00edstico\u2019. (15 al 17 de julio)<\/a><\/li>\n<\/ul>\n<p><strong>Asimismo, durante la semana se celebrar\u00e1n los siguientes cursos:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/www.upo.es\/formacionpermanente\/cursos-de-verano\/la-interpretacion-del-verso-escenico-y-poetico-la-voz-hablada-la-voz-cantada\/\">\u2018La interpretaci\u00f3n del verso esc\u00e9nico y po\u00e9tico. La voz hablada, la voz cantada. 2\u00aa edici\u00f3n\u2019<\/a> (16 al 18 de junio. Modalidad presencial).<\/li>\n<li><a href=\"https:\/\/www.upo.es\/formacionpermanente\/cursos-de-verano\/taller-una-mirada-educativa-desde-la-pedagogia-waldorf-del-nino-de-cero-a-seis-y-de-seis-a-doce-anos\/\">Taller \u2018Una mirada educativa desde la pedagog\u00eda Waldorf del ni\u00f1o de cero a seis y de seis a doce a\u00f1os\u2019 <\/a>(17 de junio. Modalidad presencial).<\/li>\n<li><a href=\"https:\/\/www.upo.es\/formacionpermanente\/cursos-de-verano\/mejorando-la-salud-de-personas-con-trastorno-mental-grave-estrategias-practicas-para-el-cuidado-integral\/\">\u2018Mejorando la salud de personas con trastorno mental grave: estrategias pr\u00e1cticas para el cuidado integral\u2019<\/a> (18 y 19 de junio. Modalidad de presencia simult\u00e1nea).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Fuente: Fundaci\u00f3n Universidad Pablo de Olavide<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tres seminarios abrir\u00e1n el pr\u00f3ximo lunes 15 de julio la programaci\u00f3n de la quinta semana de la XXII edici\u00f3n de los Cursos de Verano de la Universidad Pablo de Olavide en Carmona. Ser\u00e1n los cursos \u2018Arqueolog\u00eda de campo. 17\u00aa edici\u00f3n\u2019, \u2018Coaching vocal de alto rendimiento: preparaci\u00f3n t\u00e9cnico-vocal de audiciones, concursos y giras. 5\u00aa edici\u00f3n\u2019 y \u2018Marketing cultural y art\u00edstico\u2019. Los tres se realizar\u00e1n de forma presencial.<\/p>\n","protected":false},"author":6,"featured_media":30880319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[729],"tags":[],"class_list":["post-30883165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-verano"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30883165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30883165"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30883165\/revisions"}],"predecessor-version":[{"id":30883167,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30883165\/revisions\/30883167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30880319"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30883165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30883165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30883165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}