{"id":30883289,"date":"2024-07-29T12:47:28","date_gmt":"2024-07-29T10:47:28","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30883289"},"modified":"2024-09-04T10:01:52","modified_gmt":"2024-09-04T08:01:52","slug":"montserrat-hermosin-nombrada-letrada-en-el-gabinete-tecnico-del-tribunal-supremo","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/comunidad\/2024\/07\/montserrat-hermosin-nombrada-letrada-en-el-gabinete-tecnico-del-tribunal-supremo\/","title":{"rendered":"Montserrat Hermos\u00edn, nombrada letrada en el Gabinete T\u00e9cnico del Tribunal Supremo"},"content":{"rendered":"<figure id=\"attachment_30883290\" aria-describedby=\"caption-attachment-30883290\" style=\"width: 336px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/07\/Monserrat-Hermosin-456x570-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30883290\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/07\/Monserrat-Hermosin-456x570-1-336x420.jpg\" alt=\"La profesora de la UPO Montserrat Hermos\u00edn.\" width=\"336\" height=\"420\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/07\/Monserrat-Hermosin-456x570-1-336x420.jpg 336w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/07\/Monserrat-Hermosin-456x570-1-420x525.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/07\/Monserrat-Hermosin-456x570-1.jpg 456w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/a><figcaption id=\"caption-attachment-30883290\" class=\"wp-caption-text\">La profesora de la UPO Montserrat Hermos\u00edn.<\/figcaption><\/figure>\n<p>La profesora titular de Derecho Financiero y Tributario en la Universidad Pablo de Olavide <strong>Montserrat Hermos\u00edn \u00c1lvarez<\/strong> ha sido nombrada <strong>letrada en el Gabinete T\u00e9cnico del Tribunal Supremo<\/strong>, adscrita a la Sala Contencioso-Administrativa (Sala Tercera).<\/p>\n<p>El Tribunal Supremo, con sede en Madrid, es un \u00f3rgano jurisdiccional \u00fanico en Espa\u00f1a con jurisdicci\u00f3n en todo el territorio nacional, constituyendo el tribunal superior en todos los \u00f3rdenes (civil, penal, contencioso-administrativo y social), salvo lo dispuesto en materia de garant\u00edas y derechos constitucionales, cuya competencia corresponde al Tribunal Constitucional.<\/p>\n<p>El <strong>Gabinete T\u00e9cnico del Tribunal Supremo<\/strong> fue creado por Real Decreto 489\/1985, de 2 de abril, y se encuentra bajo la superior direcci\u00f3n ejercida por el presidente del Tribunal Supremo. Dicho Gabinete asiste a la Presidencia y a sus diferentes Salas en los procesos de admisi\u00f3n de los asuntos de que conozcan y mediante la elaboraci\u00f3n de estudios e informes que se le soliciten (art\u00edculo 61. bis Ley Org\u00e1nica del Poder Judicial).<\/p>\n<p>Est\u00e1 integrado por un director y por miembros de la Carrera judicial y otros juristas que ostentar\u00e1n la denominaci\u00f3n de Letrados del Gabinete T\u00e9cnico. Los letrados prestan sus servicios en las diferentes \u00e1reas atendiendo a su especializaci\u00f3n profesional.<\/p>\n<p><strong>Montserrat Hermos\u00edn \u00c1lvarez<\/strong> es profesora titular de Derecho Financiero y Tributario en la Universidad Pablo de Olavide de Sevilla. Se licenci\u00f3 en Derecho siendo Premio Extraordinario al Mejor Expediente de la Licenciatura en Derecho y Premio Extraordinario al Mejor Expediente de la Universidad Pablo de Olavide de Sevilla. Es Doctora en Derecho y su tesis doctoral sobre el procedimiento sancionador tributario (Aranzadi, 2008), obtuvo varios premios de investigaci\u00f3n como el Premio Extraordinario de Doctorado, primer Premio Nacional de la Asociaci\u00f3n Espa\u00f1ola de Asesores Fiscales (AEDAF), Premio Ayuntamiento de Sevilla a la Mejor Tesis Doctoral y Premio Real Maestranza de Caballer\u00eda de Investigaci\u00f3n.<\/p>\n<p>Ha realizado estancias de investigaci\u00f3n en la \u2018<em>Scuola Europea di Alti Studi Tributari<\/em>\u2019, Bolonia (Italia), en la Universidad de Oxford (Reino Unido) y en la <em>Universit\u00e9 Catholique<\/em> de Lyon (Francia). A trav\u00e9s del Programa de Movilidad Jos\u00e9 Castillejo del Ministerio de Educaci\u00f3n ha sido <em>Visiting Scholar<\/em> en el <em>Centre for Commercial Law Studies<\/em>, <em>Queen Mary University of London<\/em> (Reino Unido) y en la Universidad Fordham de Nueva York (EEUU) y, <em>Academic Visitor<\/em> en el <em>Institute of Advanced Legal Studies<\/em> (IALS), Londres (Reino Unido).<\/p>\n<p>Es autora\/coautora de numerosas publicaciones nacionales e internacionales y tiene reconocidos cuatro sexenios por la Comisi\u00f3n Nacional Evaluadora de la Actividad Investigadora, Ministerio de Educaci\u00f3n (CNEAI). Ha participado como ponente en numerosas conferencias y congresos nacionales e internacionales y ha sido miembro de numerosos proyectos de investigaci\u00f3n financiados por el Ministerio de Educaci\u00f3n y Ciencia (I+D+i) y de contratos de I+D de especial relevancia con empresas y\/o Administraciones P\u00fablicas, adem\u00e1s de investigadora principal del proyecto sobre el sector del juego y su tributaci\u00f3n.<\/p>\n<p>Ha sido docente en todas las \u00e1reas del Derecho Financiero y Tributario, tanto a nivel de grado como de postgrado siendo profesora permanente del M\u00e1ster de Gesti\u00f3n Administrativa, M\u00e1ster Oficial de Acceso a la Abogac\u00eda, adem\u00e1s de impartir docencia en el <em>LLM in European and International Tax Law<\/em>, <em>Centre for Commercial Law<\/em>, <em>Queen Mary University of London<\/em> (Reino Unido). Tiene reconocidas dos menciones de excelencia docente y cuenta con el reconocimiento p\u00fablico a la excelencia docente en el Programa DOCENTIA. Ha sido coordinadora del M\u00e1ster Oficial de Abogac\u00eda, adjunta a la Inspecci\u00f3n de Servicios de la Universidad Pablo de Olavide de Sevilla, directora acad\u00e9mica del Grado en Relaciones Laborales y Recursos Humanos y coordinadora de Movilidad de la Facultad de Derecho.<\/p>\n<p>Le ha sido concedida la Beca FULBRIGHT (2019) y ha formado parte de la comisi\u00f3n evaluadora de las Becas FULBRIGHT, Espa\u00f1a-EEUU.\u00a0 Pertenece a la Red Leonardo de Investigadores y Creadores Culturales, Fundaci\u00f3n BBVA, tras la obtenci\u00f3n de la Beca Leonardo en 2021. Desde marzo de 2023 es miembro del panel de expertos fiscales de Naciones Unidas, UNDP ExpRes Roster.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La profesora titular de Derecho Financiero y Tributario en la Universidad Pablo de Olavide Montserrat Hermos\u00edn \u00c1lvarez ha sido nombrada letrada en el Gabinete T\u00e9cnico del Tribunal Supremo, adscrita a la Sala Contencioso-Administrativa (Sala Tercera).<\/p>\n","protected":false},"author":2,"featured_media":30883290,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[5842],"tags":[7239,7284,8911,159,7266],"class_list":["post-30883289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad","tag-derecho-financiero","tag-derecho-financiero-y-tributario","tag-montserrat-hermosin-alvarez","tag-nombramiento","tag-tribunal-supremo"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30883289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30883289"}],"version-history":[{"count":1,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30883289\/revisions"}],"predecessor-version":[{"id":30883291,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30883289\/revisions\/30883291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30883290"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30883289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30883289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30883289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}