{"id":30884429,"date":"2024-11-29T14:24:50","date_gmt":"2024-11-29T13:24:50","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30884429"},"modified":"2024-12-18T17:57:24","modified_gmt":"2024-12-18T16:57:24","slug":"soledades-accion-comunitaria-sevilla-tema-central-jornada-upo","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/docencia-formacion\/2024\/11\/soledades-accion-comunitaria-sevilla-tema-central-jornada-upo\/","title":{"rendered":"Soledades y acci\u00f3n comunitaria en Sevilla, tema central de una jornada en la UPO"},"content":{"rendered":"<figure id=\"attachment_30884431\" aria-describedby=\"caption-attachment-30884431\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30884431\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-750x500.jpg\" alt=\"\" width=\"750\" height=\"500\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-750x500.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-420x280.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-768x512.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-1536x1024.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-2048x1365.jpg 2048w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-165x109.jpg 165w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades03-1320x880.jpg 1320w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-30884431\" class=\"wp-caption-text\">De izquierda a derecha, Juan Manuel Garc\u00eda Gonz\u00e1lez, Francisco Rodr\u00edguez Guanter, Roc\u00edo Barrag\u00e1n, y Rosal\u00eda Mart\u00ednez.<\/figcaption><\/figure>\n<p>La Universidad Pablo de Olavide ha acogido a lo largo de la ma\u00f1ana de hoy el encuentro <strong>\u2018Di\u00e1logos sobre soledades y acci\u00f3n comunitaria en Sevilla\u2019<\/strong>, un evento que se celebra en el marco de la <a href=\"https:\/\/www.upo.es\/investiga\/demografia-salud\/catedra-cruz-roja\/\"><strong>C\u00e1tedra Cruz Roja Sevilla<\/strong> <strong>en estudios sobre soledad no deseada<\/strong><\/a>, dirigida por el catedr\u00e1tico del Departamento de Sociolog\u00eda de la UPO <strong>Juan Manuel Garc\u00eda Gonz\u00e1lez<\/strong>.<\/p>\n<p>El foro ha sido inaugurado por <strong>Roc\u00edo Barrag\u00e1n<\/strong>, directora General de Personas Mayores, Participaci\u00f3n Activa y Soledad no deseada de la Junta de Andaluc\u00eda; <strong>Francisco Rodr\u00edguez Guanter<\/strong>, presidente de Cruz Roja en Sevilla; y <strong>Rosal\u00eda Mart\u00ednez<\/strong>, catedr\u00e1tica de Sociolog\u00eda de la UPO y miembro de la Comisi\u00f3n de C\u00e1tedra Cruz Roja en estudios sobre soledad.<\/p>\n<figure id=\"attachment_30884432\" aria-describedby=\"caption-attachment-30884432\" style=\"width: 420px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30884432\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-420x280.jpg\" alt=\"\" width=\"420\" height=\"280\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-420x280.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-750x500.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-768x512.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-1536x1024.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-2048x1365.jpg 2048w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-165x109.jpg 165w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades08-1320x880.jpg 1320w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/a><figcaption id=\"caption-attachment-30884432\" class=\"wp-caption-text\">El profesor de la UPO Juan Manuel Garc\u00eda Gonz\u00e1lez.<\/figcaption><\/figure>\n<p>Tras la inauguraci\u00f3n, Juan Manuel Garc\u00eda Gonz\u00e1lez ha presentado el libro <strong>\u2018Caracterizaci\u00f3n de hogares en situaci\u00f3n de vulnerabilidad y aislamiento social en el distrito Macarena de Sevilla\u2019<\/strong>, fruto de un <a href=\"https:\/\/www.upo.es\/diario\/ciencia\/2023\/03\/un-estudio-de-la-upo-indica-que-el-57-de-la-poblacion-estudiada-mayor-de-60-anos-se-encuentra-en-situacion-de-soledad\/\">proyecto de investigaci\u00f3n<\/a> entre Cruz Roja Sevilla y la Universidad Pablo de Olavide, pionero en el municipio hispalense.<\/p>\n<p>As\u00ed, en el marco de este estudio, se ha analizado en un \u00fanico distrito, Macarena, un aspecto fundamental de la realidad social, como es la soledad y el aislamiento social, en una poblaci\u00f3n de personas mayores de 65 a\u00f1os en un marco de creciente vulnerabilidad socioecon\u00f3mica.<\/p>\n<p>Este proyecto, de car\u00e1cter exploratorio, se ha hecho, adem\u00e1s, con una doble metodolog\u00eda: por encuesta y, como novedad, a trav\u00e9s de entrevistas a sus vecinas y vecinos de dichas edades. De este modo el equipo de investigaci\u00f3n ha podido obtener, si bien de manera incipiente, cu\u00e1les son sus <strong>inquietudes y preocupaciones acerca de las condiciones del distrito y su efecto en la soledad y el aislamiento social<\/strong>, adoptando as\u00ed una orientaci\u00f3n comunitaria muy necesaria para poder orientar las acciones para prevenir e intervenir ante ambos fen\u00f3menos.<\/p>\n<p>\u201cCon este libro cerramos el proyecto y ahora queremos ver hacia d\u00f3nde nos dirigimos, hasta qu\u00e9 punto este trabajo nos va a servir como C\u00e1tedra, como Cruz Roja, a la administraci\u00f3n auton\u00f3mica como administraci\u00f3n general que gestiona las pol\u00edticas p\u00fablicas, a la administraci\u00f3n local que gestiona gran parte de los servicios del distrito Macarena, y a las entidades del Tercer Sector y a la sociedad en general\u201d, expresa Juan Manuel Garc\u00eda Gonz\u00e1lez.<\/p>\n<figure id=\"attachment_30884433\" aria-describedby=\"caption-attachment-30884433\" style=\"width: 420px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30884433\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-420x280.jpg\" alt=\"\" width=\"420\" height=\"280\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-420x280.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-750x500.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-768x512.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-1536x1024.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-2048x1365.jpg 2048w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-165x109.jpg 165w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2024\/11\/dialogos_soledades09-1320x880.jpg 1320w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/a><figcaption id=\"caption-attachment-30884433\" class=\"wp-caption-text\">Mar\u00eda Garc\u00eda Salgado, responsable del Programa de Personas Mayores de Cruz Roja en Andaluc\u00eda.<\/figcaption><\/figure>\n<p>Tras la presentaci\u00f3n del libro, <strong>Mar\u00eda Garc\u00eda Salgado<\/strong>, responsable del Programa de Personas Mayores de Cruz Roja en Andaluc\u00eda, ha abordado las <strong>estrategias de prevenci\u00f3n e intervenci\u00f3n<\/strong> frente a las soledades que se llevan a cabo desde la entidad.<\/p>\n<p>El encuentro ha concluido con la mesa de di\u00e1logo <strong>\u2018La acci\u00f3n comunitaria como herramienta frente a las soledades\u2019<\/strong>, en la que diversos agentes sociales del tercer sector y la administraci\u00f3n p\u00fablica del municipio de Sevilla han conversado sobre el papel que tiene la comunidad \u2013entendiendo \u00e9sta como ese espacio cercano de relaciones barriales, vecinales, familiares y comerciales en el que vivimos y hacemos nuestro d\u00eda a d\u00eda\u2013 y las pol\u00edticas y programas a nivel comunitario y cercano en la co-creaci\u00f3n de entornos y ciudades m\u00e1s amigables que permitan prevenir y mitigar la soledad.<\/p>\n<h3><strong>M\u00e1s informaci\u00f3n:<\/strong><\/h3>\n<p>Libro \u2018Caracterizaci\u00f3n de hogares en situaci\u00f3n de vulnerabilidad y aislamiento social en el distrito Macarena de Sevilla\u2019. <a href=\"https:\/\/www.dropbox.com\/scl\/fi\/o4o3xu2rnrwj5h9ltpyaa\/2024_Soledades_Macarena_Cruz_Roja.pdf?rlkey=5cn14oyozvmyht7b8cdzwjuh8&amp;dl=0.\">Enlace de descarga<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Universidad Pablo de Olavide ha acogido a lo largo de la ma\u00f1ana de hoy el encuentro \u2018Di\u00e1logos sobre soledades y acci\u00f3n comunitaria en Sevilla\u2019, un evento que se celebra en el marco de la C\u00e1tedra Cruz Roja Sevilla en estudios sobre soledad no deseada, dirigida por el catedr\u00e1tico del Departamento de Sociolog\u00eda de la UPO Juan Manuel Garc\u00eda Gonz\u00e1lez.<\/p>\n","protected":false},"author":2,"featured_media":30884431,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[2779],"tags":[358,7618,5709,333,2160,38,104],"class_list":["post-30884429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-docencia-formacion","tag-catedra","tag-catedra-cruz-roja-sevilla-en-estudios-sobre-soledad-no-deseada","tag-cruz-roja-espanola","tag-libro","tag-personas-mayores","tag-rector","tag-sociologia"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30884429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30884429"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30884429\/revisions"}],"predecessor-version":[{"id":30884434,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30884429\/revisions\/30884434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30884431"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30884429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30884429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30884429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}