{"id":30888496,"date":"2025-10-23T07:01:24","date_gmt":"2025-10-23T05:01:24","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30888496"},"modified":"2025-10-28T13:52:22","modified_gmt":"2025-10-28T12:52:22","slug":"la-educacion-de-las-mujeres-impulsa-su-presencia-en-politica","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/ciencia\/2025\/10\/la-educacion-de-las-mujeres-impulsa-su-presencia-en-politica\/","title":{"rendered":"La educaci\u00f3n de las mujeres impulsa su presencia en pol\u00edtica"},"content":{"rendered":"<figure id=\"attachment_30888499\" aria-describedby=\"caption-attachment-30888499\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30888499\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg-750x440.jpg\" alt=\"Mapa comparativo de 2004 y 2018 se aprecia la fuerte heterogeneidad territorial y el avance generalizado de la representaci\u00f3n femenina en Europa; Francia, parte de Espa\u00f1a y los pa\u00edses n\u00f3rdicos se acercan a la paridad, mientras que Italia, Polonia, Hungr\u00eda o Grecia se mantienen rezagados. Pese al aumento general, la igualdad de g\u00e9nero sigue siendo limitada, en no pocas regiones las mujeres no llegan al 33 % de representaci\u00f3n.\" width=\"750\" height=\"440\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg-750x440.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg-420x246.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg-768x451.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg-1536x901.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg-2048x1202.jpg 2048w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/1-s2.0-S0272775724000992-gr1_lrg-1320x775.jpg 1320w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-30888499\" class=\"wp-caption-text\">Mapa comparativo de 2004 y 2018 donde se aprecia la fuerte heterogeneidad territorial y el avance generalizado de la representaci\u00f3n femenina en Europa; Francia, parte de Espa\u00f1a y los pa\u00edses n\u00f3rdicos se acercan a la paridad, mientras que Italia, Polonia, Hungr\u00eda o Grecia se mantienen rezagados. Pese al aumento general, la igualdad de g\u00e9nero sigue siendo limitada, con regiones en las que las mujeres no llegan al 33 % de representaci\u00f3n.<\/figcaption><\/figure>\n<p>En las \u00faltimas d\u00e9cadas, la participaci\u00f3n pol\u00edtica de las mujeres ha crecido en todo el mundo, pero el camino hacia la paridad sigue siendo largo. En 2021, las mujeres ocupaban solo el 26 % de los esca\u00f1os parlamentarios a nivel global y menos del 6 % de las jefaturas de gobierno. Seg\u00fan el <a href=\"https:\/\/es.weforum.org\/publications\/global-gender-gap-report-2025\/\"><em>Global Gender Gap Index<\/em><\/a> del Foro Econ\u00f3mico Mundial, la brecha de g\u00e9nero en la esfera pol\u00edtica es la m\u00e1s profunda de todas las dimensiones analizadas, m\u00e1s que en educaci\u00f3n, salud o participaci\u00f3n econ\u00f3mica.<\/p>\n<p>Una de las claves para disminuir esta diferencia est\u00e1 en la educaci\u00f3n. Cuando las mujeres estudian m\u00e1s, la democracia se vuelve m\u00e1s igualitaria. Esa es la principal conclusi\u00f3n del art\u00edculo cient\u00edfico <strong><em>Bridging the gender gap: Women\u2019s education and political representation<\/em><\/strong>, publicado en <em>Economics of Education Review<\/em>, y firmado por <strong><a href=\"https:\/\/sites.google.com\/site\/lunabellani\/\">Luna Bellani<\/a><\/strong> (Ulm University, IZA y AXA Research Lab on Gender) y <strong><a href=\"https:\/\/sites.google.com\/view\/marisahidalgo-hidalgo\/home\">Marisa Hidalgo<\/a><\/strong>, profesora de An\u00e1lisis Econ\u00f3mico de la Universidad Pablo de Olavide. El trabajo encuentra que <strong>un incremento de un punto porcentual en la proporci\u00f3n de mujeres con estudios secundarios eleva en torno a un 21 % la cuota de mujeres electas en los parlamentos regionales.<\/strong><\/p>\n<p><strong>Las investigadoras combinaron datos de nueve pa\u00edses europeos<\/strong> (Austria, Rep\u00fablica Checa, Francia, Alemania, Grecia, Hungr\u00eda, Pa\u00edses Bajos, Polonia y Eslovaquia) entre 2003 y 2018. <strong>Al cruzar la proporci\u00f3n anual de mujeres electas en parlamentos regionales<\/strong> \u2014obtenida del <em>Gender Statistics Database<\/em> del Instituto Europeo de Igualdad de G\u00e9nero (EIGE)\u2014 <strong>con actitudes pol\u00edticas y roles de g\u00e9nero, adem\u00e1s de informaci\u00f3n detallada sobre caracter\u00edsticas sociodemogr\u00e1ficas (incluida los a\u00f1os de estudio) a nivel individual<\/strong> \u2014observados por el <em>European Social Survey<\/em> (ESS)\u2014, identifican un efecto causal. Mediante un modelo econom\u00e9trico con variables instrumentales, las autoras han aprovechado las reformas educativas que ampliaron la escolarizaci\u00f3n obligatoria en los a\u00f1os sesenta y setenta \u2014reformas que afectaron a distintos pa\u00edses en momentos diferentes\u2014, trat\u00e1ndolas como \u2018experimentos naturales\u2019 que <strong>permiten identificar un efecto causal de la proporci\u00f3n de mujeres que alcanzan un nivel educativo sobre la representaci\u00f3n femenina en los parlamentos regionales<\/strong>.<\/p>\n<figure id=\"attachment_30888498\" aria-describedby=\"caption-attachment-30888498\" style=\"width: 420px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-30888498\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-420x236.jpg\" alt=\"Marisa Hidalgo\" width=\"420\" height=\"236\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-420x236.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-750x422.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-768x432.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-1536x864.jpg 1536w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-2048x1152.jpg 2048w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2025\/10\/Marisa-Hidalgo-1320x743.jpg 1320w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/a><figcaption id=\"caption-attachment-30888498\" class=\"wp-caption-text\">Marisa Hidalgo, profesora de An\u00e1lisis Econ\u00f3mico<\/figcaption><\/figure>\n<p>\u00abEl uso de variables instrumentales nos permite identificar el efecto de la educaci\u00f3n sobre aquellas personas que, de no haberse aplicado la reforma, habr\u00edan dejado los estudios antes, los denominados \u2018<em>compliers<\/em>\u2019\u00bb, afirma <strong>Marisa Hidalgo<\/strong>. En la muestra analizada, una de cada cuatro mujeres de esas generaciones no super\u00f3 el nivel educativo previo a la reforma, frente a uno de cada diez hombres. Las principales beneficiarias de la extensi\u00f3n de la escolaridad fueron j\u00f3venes de hogares con menos recursos (padre en desempleo, familias monoparentales) y, en su mayor\u00eda, con progenitores sin estudios (92 %). \u00abPor tanto, el aumento del 21 % en la representaci\u00f3n pol\u00edtica femenina que documentamos refleja, sobre todo, el efecto positivo de prolongar la educaci\u00f3n entre las mujeres que part\u00edan de entornos m\u00e1s desfavorecidos. Mejorar su nivel educativo no solo ampli\u00f3 sus oportunidades personales y laborales, sino que tambi\u00e9n tuvo un impacto duradero en la participaci\u00f3n de mujeres en la vida p\u00fablica y en pol\u00edtica\u00bb.<\/p>\n<p><strong>La importancia de contar con iniciativas que reduzcan la brecha de g\u00e9nero existente en pol\u00edtica ha sido una de las principales motivaciones del estudio llevado a cabo por Hidalgo y Bellani<\/strong>. \u00abNos llam\u00f3 la atenci\u00f3n la abundancia de literatura mostrando evidencia de los beneficios asociados a la participaci\u00f3n de la mujer en los procesos de toma de decisiones colectivas y, sin embargo, la escasez, por no decir ausencia, de trabajos sobre dise\u00f1o de pol\u00edticas p\u00fablicas dirigidas a reducir la enorme brecha de g\u00e9nero en este \u00e1mbito, sobre todo en pa\u00edses desarrollados\u00bb, afirma Marisa Hidalgo.<\/p>\n<h3><strong>Mayor inter\u00e9s pol\u00edtico y actitudes m\u00e1s igualitarias<\/strong><\/h3>\n<p>Adem\u00e1s del resultado principal, Hidalgo y Bellani indagan en las posibles causas, que podr\u00edan tener un componente de oferta (m\u00e1s mujeres con ambici\u00f3n y preparaci\u00f3n pol\u00edtica) y de demanda (electorados e instituciones m\u00e1s receptivos). As\u00ed, encuentran que las mujeres con mayor educaci\u00f3n declaran m\u00e1s inter\u00e9s por la pol\u00edtica y adoptan actitudes m\u00e1s igualitarias sobre los roles de g\u00e9nero, cambios que no se observan en los hombres con el mismo aumento educativo. Estos mecanismos ayudan a entender por qu\u00e9 los parlamentos con poblaciones femeninas m\u00e1s educadas cuentan con m\u00e1s mujeres.<\/p>\n<p><strong>Referencia:<br \/>\n<\/strong>Bellani, L., &amp; Hidalgo-Hidalgo, M. (2025). <strong>Bridging the gender gap: Women\u2019s education and political representation<\/strong>. <em>Economics Of Education Review, 104<\/em>, 102605. <a href=\"https:\/\/doi.org\/10.1016\/j.econedurev.2024.102605\">https:\/\/doi.org\/10.1016\/j.econedurev.2024.102605<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un estudio con participaci\u00f3n de la Universidad Pablo de Olavide demuestra que elevar el nivel educativo femenino aumenta de forma significativa la representaci\u00f3n pol\u00edtica de las mujeres en los parlamentos regionales europeos.<\/p>\n","protected":false},"author":6,"featured_media":30888499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[553,465,454,5883,138,1170,7665,104],"class_list":["post-30888496","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","tag-analisis-economico","tag-educacion","tag-europa","tag-igualdad-de-genero","tag-parlamento","tag-politicas-publicas","tag-roles-de-genero","tag-sociologia"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30888496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30888496"}],"version-history":[{"count":4,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30888496\/revisions"}],"predecessor-version":[{"id":30888501,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30888496\/revisions\/30888501"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30888499"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30888496"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30888496"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30888496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}