{"id":30891093,"date":"2026-05-13T12:27:44","date_gmt":"2026-05-13T10:27:44","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=30891093"},"modified":"2026-05-13T12:29:11","modified_gmt":"2026-05-13T10:29:11","slug":"investigadoras-de-la-upo-analizan-la-brecha-de-genero-en-el-emprendimiento-universitario-y-su-impacto-en-el-bienestar-de-las-estudiantes","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/ciencia\/2026\/05\/investigadoras-de-la-upo-analizan-la-brecha-de-genero-en-el-emprendimiento-universitario-y-su-impacto-en-el-bienestar-de-las-estudiantes\/","title":{"rendered":"Investigadoras de la UPO analizan la brecha de g\u00e9nero en el emprendimiento universitario y su impacto en el bienestar de las estudiantes"},"content":{"rendered":"<figure id=\"attachment_30891095\" aria-describedby=\"caption-attachment-30891095\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/informe-GUESSS_presentacion.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-30891095\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/informe-GUESSS_presentacion-750x506.jpg\" alt=\"Presentaci\u00f3n del informe GUESSS Mujeres 2023\" width=\"750\" height=\"506\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/informe-GUESSS_presentacion-750x506.jpg 750w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/informe-GUESSS_presentacion-420x283.jpg 420w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/informe-GUESSS_presentacion-768x518.jpg 768w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/informe-GUESSS_presentacion.jpg 1183w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-30891095\" class=\"wp-caption-text\">Presentaci\u00f3n del informe GUESSS 2023<\/figcaption><\/figure>\n<p>El emprendimiento no solo abre una v\u00eda profesional para las estudiantes universitarias, tambi\u00e9n puede convertirse en una herramienta de bienestar, confianza y resiliencia. Esta es una de las principales conclusiones del informe \u2018<strong>GUESSS 2023. Mujeres que emprenden, mujeres que crecen: el emprendimiento como motor de bienestar, autoeficacia y resiliencia en las mujeres<\/strong>\u2019, presentado recientemente en Madrid y elaborado por las profesoras de la Universidad Pablo de Olavide Ana P\u00e9rez-Lu\u00f1o y Elena Sousa Ginel, del centro propio de investigaci\u00f3n de la UPO <a href=\"https:\/\/www.upo.es\/inn-lab\/\">InnLab<\/a>, junto al catedr\u00e1tico em\u00e9rito de la Universidad de C\u00e1diz Jos\u00e9 Ruiz Navarro.<\/p>\n<p>El estudio ofrece una radiograf\u00eda del emprendimiento femenino en la universidad espa\u00f1ola y pone el foco en una cuesti\u00f3n importante: aunque las estudiantes siguen mostrando menores niveles de intenci\u00f3n y actividad emprendedora que sus compa\u00f1eros varones, aquellas que se acercan al emprendimiento \u2014ya sea como aspiraci\u00f3n, proyecto naciente o empresa activa\u2014 declaran mayores niveles de bienestar subjetivo, autoeficacia y resiliencia.<\/p>\n<p>Seg\u00fan el informe, solo el 9,6% de las universitarias espa\u00f1olas afirma querer fundar su propia empresa al finalizar sus estudios, frente al 16,9% de los hombres. A cinco a\u00f1os vista, la intenci\u00f3n emprendedora aumenta en ambos grupos, pero la brecha se ampl\u00eda: 19,2 % en mujeres frente al 28,8% en hombres. Las diferencias tambi\u00e9n se mantienen en la actividad emprendedora: el 13,2% de las mujeres est\u00e1 involucrado en iniciativas nacientes, frente al 24,5% de los hombres, y solo el 5,9 % posee una empresa activa mientras estudia, frente al 10,8% de ellos.<\/p>\n<p>Pero el estudio tambi\u00e9n apunta que las universitarias que manifiestan intenci\u00f3n de emprender presentan una media de bienestar de 5,01 sobre 7, superior a la de quienes no lo desean. Adem\u00e1s, cuando las mujeres ya tienen una empresa en funcionamiento, alcanzan los niveles m\u00e1s altos de bienestar registrados en el estudio: 5,06 sobre 7, una puntuaci\u00f3n id\u00e9ntica a la de los hombres emprendedores activos. Para las autoras, este dato es especialmente relevante porque muestra que la brecha de g\u00e9nero pr\u00e1cticamente desaparece cuando las mujeres logran consolidar sus proyectos empresariales.<\/p>\n<p>La investigaci\u00f3n tambi\u00e9n analiza dos <strong>dimensiones psicol\u00f3gicas decisivas para emprender: la autoeficacia<\/strong>, entendida como la confianza en las propias capacidades para identificar oportunidades, desarrollar productos o comercializar ideas, <strong>y la resiliencia,<\/strong> es decir, la capacidad para afrontar situaciones dif\u00edciles y adaptarse a ellas. En ambos casos, las estudiantes parten de valores algo inferiores a los de sus compa\u00f1eros, pero la distancia se reduce notablemente entre quienes emprenden. Las mujeres involucradas en emprendimiento naciente alcanzan una autoeficacia media de 5,51, frente al 4,62 de las que no est\u00e1n emprendiendo.<\/p>\n<p>El informe se\u00f1ala, no obstante, que persisten <strong>obst\u00e1culos estructurales<\/strong>. Uno de los m\u00e1s relevantes es el acceso a la formaci\u00f3n emprendedora: solo el 29,7% de las estudiantes universitarias ha recibido alg\u00fan tipo de formaci\u00f3n espec\u00edfica en emprendimiento, frente al 34,8% de los hombres, un dato que adem\u00e1s supone un retroceso respecto a 2021. Tambi\u00e9n se observa una menor presencia femenina en ramas STEM, entre las universitarias encuestadas, el 9,9% estudia Ingenier\u00eda y Arquitectura; entre los hombres, ese porcentaje asciende al 23,9%.<\/p>\n<p>El reporte concluye que <strong>las universidades desempe\u00f1an un papel estrat\u00e9gico para reducir la brecha de g\u00e9nero en el emprendimiento<\/strong>. Entre sus recomendaciones figuran ampliar el alcance de la formaci\u00f3n emprendedora, evaluar su impacto real en las pol\u00edticas universitarias, incorporar una perspectiva de g\u00e9nero en los programas formativos y visibilizar referentes femeninos diversos. GUESSS 2023 recomienda dise\u00f1ar itinerarios formativos adaptados a la diversidad de trayectorias, motivaciones y capacidades de las estudiantes.<\/p>\n<h3><strong>GUESSS<\/strong><\/h3>\n<p><a href=\"https:\/\/observatoriodelemprendimiento.es\/guesss\/wp-content\/uploads\/2026\/04\/GUESSS%20Mujeres%202023.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright size-large wp-image-30891094\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/GUESSS-Mujeres-2023-portada-379x525.jpg\" alt=\"GUESSS 2023. Mujeres que emprenden, mujeres que crecen: el emprendimiento como motor de bienestar, autoeficacia y resiliencia en las mujeres\" width=\"379\" height=\"525\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/GUESSS-Mujeres-2023-portada-379x525.jpg 379w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/GUESSS-Mujeres-2023-portada-303x420.jpg 303w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2026\/05\/GUESSS-Mujeres-2023-portada.jpg 595w\" sizes=\"auto, (max-width: 379px) 100vw, 379px\" \/><\/a><a href=\"https:\/\/www.guesssurvey.org\/\"><em>Global University Entrepreneurial Spirit Students\u2019 Survey<\/em><\/a> (GUESSS) es un proyecto internacional que analiza las intenciones y actividades emprendedoras del estudiantado universitario, as\u00ed como los factores que influyen en ellas. En su d\u00e9cima edici\u00f3n internacional, con datos de 2023, el estudio reuni\u00f3 respuestas de m\u00e1s de 226.000 estudiantes de 1.300 universidades en 57 pa\u00edses. En <a href=\"https:\/\/observatoriodelemprendimiento.es\/guesss\/\">Espa\u00f1a<\/a> el proyecto GUESSS est\u00e1 organizado por el Observatorio del Emprendimiento y en los datos de 2023 han participado 78.889 estudiantes de 71 universidades. GUESSS 2023 cuenta con la colaboraci\u00f3n de ENISA (Ministerio de Industria y Turismo), SANFI (<em>Santander Financial Institute<\/em>), Reale Seguros y la participaci\u00f3n de EOI.<\/p>\n<p><strong>Referencia:<br \/>\n<\/strong>P\u00e9rez, A., Sousa, E., &amp; Ruiz, J. (s.\u00a0f.). <strong>GUESSS 2023. Mujeres que emprenden, mujeres que crecen: el emprendimiento como motor de bienestar, autoeficacia y resiliencia en las mujeres<\/strong>. En <em>https:\/\/observatoriodelemprendimiento.es\/guesss<\/em> (ISBN: 978-84-09-75528-8). Observatorio del Emprendimiento de Espa\u00f1a. <a href=\"https:\/\/observatoriodelemprendimiento.es\/guesss\/wp-content\/uploads\/2026\/04\/GUESSS%20Mujeres%202023.pdf\">https:\/\/observatoriodelemprendimiento.es\/guesss\/wp-content\/uploads\/2026\/04\/GUESSS%20Mujeres%202023.pdf<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El informe GUESSS 2023, elaborado por Ana P\u00e9rez Lu\u00f1o, Elena Sousa Ginel y Jos\u00e9 Ruiz Navarro, revela que las universitarias emprenden menos que sus compa\u00f1eros, aunque quienes lo hacen muestran mayores niveles de bienestar, autoeficacia y resiliencia.<\/p>\n","protected":false},"author":6,"featured_media":30891095,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[3],"tags":[99,689,21,2349,8688,8130,554,39],"class_list":["post-30891093","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","tag-creacion-de-empresas","tag-emprendimiento","tag-estudiantes","tag-genero-e-igualdad","tag-informe-guesss","tag-innlab","tag-innovacion","tag-universidades"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30891093","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=30891093"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30891093\/revisions"}],"predecessor-version":[{"id":30891097,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/30891093\/revisions\/30891097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/30891095"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=30891093"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=30891093"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=30891093"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}