{"id":327025,"date":"2013-01-24T06:39:36","date_gmt":"2013-01-24T06:39:36","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=327025"},"modified":"2013-01-24T12:05:23","modified_gmt":"2013-01-24T12:05:23","slug":"manana-jueves-se-presenta-en-la-upo-la-primera-edicion-del-curso-tecnicas-de-consultoria","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/institucional\/2013\/01\/manana-jueves-se-presenta-en-la-upo-la-primera-edicion-del-curso-tecnicas-de-consultoria\/","title":{"rendered":"Hoy jueves se presenta en la UPO la primera edici\u00f3n del curso \u00abT\u00e9cnicas de Consultor\u00eda\u00bb"},"content":{"rendered":"<p>Hoy jueves, a las 19 horas, en la sala de grados del edificio 7 de la Universidad Pablo de Olavide, se presentar\u00e1 la primera edici\u00f3n del curso \u201c<a href=\"http:\/\/www.fundaciones.upo.es\/web\/fundacion-universidad-sociedad\/ciencias-sociales-economicas-y-juridicas1?p_p_id=101_INSTANCE_4tWi&amp;p_p_lifecycle=0&amp;p_p_state=maximized&amp;p_p_mode=view&amp;p_p_col_id=column-1&amp;p_p_col_pos=1&amp;p_p_col_count=2&amp;_101_INSTANCE_4tWi_struts_action=%2Fasset_publisher%2Fview_content&amp;_101_INSTANCE_4tWi_urlTitle=tecnicas-de-consultoria-i-edicion&amp;_101_INSTANCE_4tWi_type=content&amp;_101_INSTANCE_4tWi_redirect=%2Fweb%2Ffundacion-universidad-sociedad%2Fciencias-sociales-economicas-y-juridicas1\">T\u00e9cnicas de Consultor\u00eda<\/a>\u201d, un t\u00edtulo propio de esta Universidad que permitir\u00e1 a los alumnos especializarse en uno de los sectores que mejor est\u00e1 respondiendo en la actual situaci\u00f3n econ\u00f3mica.<\/p>\n<p>En concreto, a la presentaci\u00f3n asistir\u00e1n Juan Jos\u00e9 Roca Mu\u00f1oz, director cient\u00edfico del curso, y Jos\u00e9 Antonio Gallardo, vocal de Formaci\u00f3n de la Red Andaluza de Consultores Independientes. Durante el acto, intervendr\u00e1n los directores y organizadores de este curso que explicar\u00e1n la importancia de la consultor\u00eda y los contenidos que se desarrollar\u00e1n a lo largo de los tres meses que durar\u00e1 esta actividad.<\/p>\n<p>Este curso de formaci\u00f3n especializada, que comenzar\u00e1 a partir del 14 de febrero, se impartir\u00e1 los jueves y viernes en horario de 16 a 20 horas, y est\u00e1 dirigido a diplomados, licenciados, profesionales y estudiantes relacionados con la gesti\u00f3n empresarial y, en general, a cualquier persona interesada en la tem\u00e1tica.<\/p>\n<p>Durante las diferentes sesiones, se abordar\u00e1n cinco m\u00f3dulos en los que se realizar\u00e1 una introducci\u00f3n a la consultor\u00eda y se profundizar\u00e1 en las herramientas de an\u00e1lisis, en la gesti\u00f3n de proyectos, en el marketing de servicios y en la importancia de las habilidades directivas para el consultor.<\/p>\n<p>Las personas interesadas pueden ampliar esta informaci\u00f3n en la p\u00e1gina web de la Fundaci\u00f3n Universidad &#8211; Sociedad de la Universidad Pablo de Olavide, en el siguiente enlace: <a href=\"http:\/\/www.fundaciones.upo.es\/web\/fundacion&lt;\/a&gt;-universidad-sociedad\/ciencias-sociales-economicas-y-juridicas1\" target=\"_BLANK\">www.fundaciones.upo.es<\/a>, o bien contactando con la Unidad de Formaci\u00f3n Permanente en el correo <a href=\"mailto:formacionpermanente@fundacion.upo\">formacionpermanente@fundacion.upo<\/a>.es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy  jueves, a las 19 horas, en la sala de grados del edificio 7 de la Universidad Pablo de Olavide, se presentar\u00e1 la primera edici\u00f3n del curso \u201cT\u00e9cnicas de Consultor\u00eda\u201d, un t\u00edtulo propio de esta Universidad que permitir\u00e1 a los alumnos especializarse en uno de los sectores que mejor est\u00e1 respondiendo en la actual situaci\u00f3n econ\u00f3mica. <\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[165,141,47,166],"class_list":["post-327025","post","type-post","status-publish","format-standard","hentry","category-institucional","tag-consultoria","tag-curso","tag-fundaciones","tag-titulo-propio"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/327025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=327025"}],"version-history":[{"count":9,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/327025\/revisions"}],"predecessor-version":[{"id":327362,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/327025\/revisions\/327362"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=327025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=327025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=327025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}