{"id":4884717,"date":"2014-07-21T22:00:39","date_gmt":"2014-07-21T22:00:39","guid":{"rendered":"https:\/\/www.upo.es\/diario\/?p=4884717"},"modified":"2014-07-21T22:00:40","modified_gmt":"2014-07-21T22:00:40","slug":"las-campanas-publicitarias-actuales-deben-crear-vinculos-afectivos-con-los-consumidores","status":"publish","type":"post","link":"https:\/\/www.upo.es\/diario\/cursos-verano\/2014\/07\/las-campanas-publicitarias-actuales-deben-crear-vinculos-afectivos-con-los-consumidores\/","title":{"rendered":"\u201cLas campa\u00f1as publicitarias actuales deben crear v\u00ednculos afectivos con los consumidores\u201d"},"content":{"rendered":"<figure id=\"attachment_488471\" aria-describedby=\"caption-attachment-488471\" style=\"width: 320px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2014\/07\/AlfonsoMendiz1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4884718\" alt=\"AlfonsoMendiz1\" src=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2014\/07\/AlfonsoMendiz1-320x239.jpg\" width=\"320\" height=\"239\" srcset=\"https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2014\/07\/AlfonsoMendiz1-320x239.jpg 320w, https:\/\/www.upo.es\/diario\/wp-content\/uploads\/2014\/07\/AlfonsoMendiz1.jpg 507w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a><figcaption id=\"caption-attachment-488471\" class=\"wp-caption-text\">Alfonso M\u00e9ndiz<\/figcaption><\/figure>\n<p>El profesor del Departamento de Comunicaci\u00f3n Audiovisual y Publicidad de la Universidad de M\u00e1laga, <strong>Alfonso M\u00e9ndiz<\/strong> ha resaltado la importancia de las emociones en el sector de la publicidad. M\u00e9ndiz ha confesado que las campa\u00f1as\u00a0 de hoy d\u00eda <strong>\u201cdemuestran que no se trata tanto de hablar de los propios productos como de crear v\u00ednculos afectivos con los consumidores y con los p\u00fablicos potenciales\u201d<\/strong>.<\/p>\n<p>M\u00e9ndez ha realizado estas declaraciones con motivo de su participaci\u00f3n en el seminario <strong>\u201cCreatividad y nuevas formas publicitarias\u201d<\/strong> que se est\u00e1 realizando en el marco de los cursos de verano que la Universidad Pablo de Olavide organiza en su sede de Carmona y del cual es director.<\/p>\n<p>Alfonso M\u00e9ndiz ha destacado la \u00faltima campa\u00f1a de Danone como especialmente significativa en la tendencia actual de vender estilos de vida y experiencias; en ella, contin\u00faa el profesor universitario, se aboga por la sonrisa;\u00a0 as\u00ed, el nombre de la campa\u00f1a es \u201cAlimenta sonrisas\u201d y nos transmite los m\u00faltiples beneficios de la misma: \u201cnos cambia la cara y el estado de \u00e1nimo, alarga nuestra existencia y nuestras ganas de vivir, nos produce un estado de bienestar y nos acerca a los dem\u00e1s.\u201d<\/p>\n<p>Para M\u00e9ndiz el objetivo de la publicidad es persuadir, cambiar una actitud o reforzar la adhesi\u00f3n ya sea en el plano comercial, social o pol\u00edtico. El experto en publicidad considera que dicha disciplina ha sido esencialmente la misma desde sus or\u00edgenes, aunque hace hincapi\u00e9 en que la tecnolog\u00eda ha ampliado notablemente su \u00e1mbito de influencia: \u201cla publicidad es esencialmente la misma, los antiguos voceadores romanos, \u2018praecos\u2019, que se contrataban para anunciar a gritos las mercanc\u00edas derivaron a los pregoneros medievales y despu\u00e9s a los vendedores ambulantes. \u00c9stos siguen cumpliendo las mismas funciones, aunque ahora los mensajes lleguen a m\u00e1s gente\u201d.<\/p>\n<p>En lo referente a los componentes que debe tener una buena campa\u00f1a de publicidad, Alfonso M\u00e9ndiz ha destacado que \u00e9sta debe \u201catraer, emocionar y transmitir un mensaje claro\u201d. Estas caracter\u00edsticas no tienen por qu\u00e9 verse modificadas en la publicidad del futuro, aunque el profesor de Comunicaci\u00f3n Audiovisual presagia importantes cambios: \u201cgracias a Internet, la publicidad se ha vuelto interactiva, las marcas se integran en las pel\u00edculas, en las teleseries y en nuestra vida cotidiana, por lo que no sufren el rechazo que antes ten\u00edan las interrupciones publicitarias; del mismo modo las marcas ya no buscan persuadir sino divertir. Es decir, los tres grandes principios de la publicidad; comunicaci\u00f3n unidireccional, separaci\u00f3n de los contenidos informativos y orientaci\u00f3n a la persuasi\u00f3n, est\u00e1n siendo reinventados en las nuevas formas de publicidad\u201d.<\/p>\n<p>Alfonso M\u00e9ndiz aborda el tema de la promoci\u00f3n tur\u00edstica de ciertas ciudades por su aparici\u00f3n en el cine. Seg\u00fan el experto, el rodaje de una pel\u00edcula en una ciudad puede otorgar a \u00e9sta popularidad, imagen internacional y atracci\u00f3n tur\u00edstica. Adem\u00e1s, puede suponer ayuda para las industrias locales, provocadas por pernoctaciones del equipo, contrataci\u00f3n de extras, artistas y t\u00e9cnicos, alquiler de equipos, etc.: \u201clos beneficios econ\u00f3micos son m\u00faltiples\u201d.<\/p>\n<p>Para que una ciudad resulte atractiva como escenario de un rodaje, M\u00e9ndiz considera que se deben facilitar\u00a0 los tr\u00e1mites y los permisos de rodaje: \u201clo m\u00e1s deseado por las productoras son las exenciones fiscales, que ahorran gastos cuantiosos y con frecuencia engorrosos\u201d.<\/p>\n<p>Como ciudades beneficiadas por este tipo de publicidad, el profesor universitario cita a Barcelona, Bu\u00f1ol, Pamplona, Sevilla, Ronda y Grazalema. Asimismo, M\u00e9ndiz se detiene de una manera especial en Almer\u00eda y Fuerteventura, ya que han albergado la \u00faltima s\u00faper producci\u00f3n filmada en nuestro pa\u00eds, \u201cExodus\u201d. Seg\u00fan ha explicado, durante los tres meses que dur\u00f3 el rodaje se produjo una gran cantidad de ingresos, siendo Almer\u00eda la \u00fanica provincia andaluza en la que se cre\u00f3 empleo en ese per\u00edodo. \u201cCuando se estrene el filme, la Spain Film Comission tiene pensada la creaci\u00f3n de rutas tur\u00edsticas en torno a los lugares en los que se rod\u00f3 la pel\u00edcula\u201d, concluye Alfonso M\u00e9ndiz.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El profesor del Departamento de Comunicaci\u00f3n Audiovisual y Publicidad de la Universidad de M\u00e1laga, Alfonso M\u00e9ndiz ha resaltado la importancia de las emociones en el sector de la publicidad. <\/p>\n","protected":false},"author":9,"featured_media":4884719,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[729],"tags":[23,22,1655,502,491],"class_list":["post-4884717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cursos-verano","tag-carmona","tag-cursos-de-verano","tag-pablo-de-olavide","tag-universidad","tag-upo"],"_links":{"self":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/4884717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/comments?post=4884717"}],"version-history":[{"count":3,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/4884717\/revisions"}],"predecessor-version":[{"id":4884721,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/posts\/4884717\/revisions\/4884721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media\/4884719"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/media?parent=4884717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/categories?post=4884717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upo.es\/diario\/wp-json\/wp\/v2\/tags?post=4884717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}