{"id":17074,"date":"2023-01-30T12:37:56","date_gmt":"2023-01-30T11:37:56","guid":{"rendered":"https:\/\/www.upo.es\/formacionpermanente\/?post_type=microcredenciales&#038;p=17074"},"modified":"2023-10-03T12:29:36","modified_gmt":"2023-10-03T10:29:36","slug":"auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912","status":"publish","type":"microcredenciales","link":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/","title":{"rendered":"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17074\" class=\"elementor elementor-17074\" data-elementor-post-type=\"microcredenciales\">\n\t\t\t\t\t\t<section data-dce-background-image-url=\"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/01\/2023ci29-scaled.jpg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-61336f52 elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default elementor-section-items-middle\" data-id=\"61336f52\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4599bced\" data-id=\"4599bced\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47ade147 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47ade147\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div data-dce-background-color=\"#00335B\" class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a56a69e\" data-id=\"a56a69e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#FAB54C\" class=\"elementor-element elementor-element-6ab937c elementor-widget elementor-widget-heading\" data-id=\"6ab937c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Microcredencial<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-3f906492 elementor-widget elementor-widget-heading\" data-id=\"3f906492\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912)<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35243a80\" data-id=\"35243a80\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-color=\"#00335B\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7a0415d0 elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7a0415d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-38ab0413\" data-id=\"38ab0413\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ff6aba5 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1ff6aba5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-shrink\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Capa_1\" x=\"0px\" y=\"0px\" viewBox=\"0 0 640 512\" style=\"enable-background:new 0 0 640 512;\" xml:space=\"preserve\"><path d=\"M59.4,32C43,32,29.7,45.3,29.7,61.7v118.8h29.7V61.7h178.2v118.8h29.7V61.7c0-16.4-13.3-29.7-29.7-29.7H59.4z M8.9,195.4 c-4.9,0-8.9,4-8.9,8.9c0,19.7,16,35.6,35.6,35.6h225.7c19.7,0,35.6-16,35.6-35.6c0-4.9-4-8.9-8.9-8.9H8.9z\"><\/path><path d=\"M386.1,324.1c-22.4,0-40.6-18.2-40.6-40.6s18.2-40.6,40.6-40.6s40.6,18.2,40.6,40.6S408.6,324.1,386.1,324.1z M573,324.1 c-22.4,0-40.6-18.2-40.6-40.6s18.2-40.6,40.6-40.6s40.6,18.2,40.6,40.6S595.4,324.1,573,324.1z M313,394.6 c0-29.9,24.3-54.2,54.2-54.2h21.7c8.1,0,15.7,1.8,22.6,4.9c-0.7,3.7-1,7.5-1,11.3c0,19.4,8.5,36.8,22,48.8c-0.1,0-0.2,0-0.4,0H323.8 C317.9,405.4,313,400.5,313,394.6z M518.8,405.4c-0.1,0-0.2,0-0.4,0c13.5-11.9,22-29.4,22-48.8c0-3.9-0.4-7.6-1-11.3 c6.9-3.2,14.6-4.9,22.6-4.9h21.7c29.9,0,54.2,24.3,54.2,54.2c0,6-4.9,10.8-10.8,10.8H518.8z M524.2,356.6 c0,26.9-21.8,48.8-48.8,48.8s-48.8-21.8-48.8-48.8s21.8-48.8,48.8-48.8S524.2,329.7,524.2,356.6z M378,489.3 c0-37.4,30.3-67.7,67.7-67.7h59.6c37.4,0,67.7,30.3,67.7,67.7c0,7.5-6,13.6-13.6,13.6H391.6C384.1,502.9,378,496.8,378,489.3z\"><\/path><g>\t<rect x=\"-8.6\" y=\"240.4\" transform=\"matrix(0.7071 -0.7071 0.7071 0.7071 -86.3516 296.3083)\" width=\"646.3\" height=\"24\"><\/rect><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-1a34d0ae elementor-widget elementor-widget-heading\" data-id=\"1a34d0ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00edbrida<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-43082c5f\" data-id=\"43082c5f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-186ff47f elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"186ff47f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-shrink\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-calendar-alt\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-2734bc8c elementor-widget elementor-widget-heading\" data-id=\"2734bc8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Del 10\/02\/2023<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-65bb4b67 elementor-widget elementor-widget-heading\" data-id=\"65bb4b67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">al 13\/05\/2026<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-56ff076d\" data-id=\"56ff076d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58953497 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"58953497\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-shrink\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-university\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-773283a5 elementor-widget elementor-widget-heading\" data-id=\"773283a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">9 ECTS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-769526df elementor-widget elementor-widget-heading\" data-id=\"769526df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">67,5 horas de docencia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-4a12c4d2\" data-id=\"4a12c4d2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-587805a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"587805a3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-66eacaf9\" data-id=\"66eacaf9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f63e669 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"f63e669\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon elementor-animation-shrink\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-euro-sign\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-dce-title-color=\"#FFFFFF\" class=\"elementor-element elementor-element-40647ca4 elementor-widget elementor-widget-heading\" data-id=\"40647ca4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">1.208 \u20ac<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-51fa8e4f\" data-id=\"51fa8e4f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d65fbd elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8d65fbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Matr\u00edcula cerrada<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a6c6843 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a6c6843\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-353015c6\" data-id=\"353015c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-475ffd9d elementor-widget elementor-widget-heading\" data-id=\"475ffd9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Presentaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7341948c elementor-widget elementor-widget-text-editor\" data-id=\"7341948c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>El curso Auditor Jefe de Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 acreditado por el Registro Internacional de Auditores Certificados (IRCA) aporta los conocimientos necesarios para auditar cualquier tipo de organizaci\u00f3n en base a los est\u00e1ndares de la Norma ISO.<\/p><p>El curso es impartido por profesores altamente cualificados, con amplia experiencia docente en estas materias y reconocimiento profesional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db38c4d\" data-id=\"db38c4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a0abe85 elementor-widget elementor-widget-heading\" data-id=\"1a0abe85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Entidad colaboradora<\/h6>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-942b696 elementor-widget elementor-widget-image\" data-id=\"942b696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.bureauveritasformacion.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/elementor\/thumbs\/Bureau-Veritas-Formacion-q3txtwros6rz49gpbxkfqs6mj27svhentqa178s33k.jpg\" title=\"Bureau Veritas Formaci\u00f3n &#8211; Microcredenciales\" alt=\"Bureau Veritas Formaci\u00f3n - Microcredenciales\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-dce-background-image-url=\"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2022\/10\/pauloramalho-0514-7909-scaled.jpg\" class=\"elementor-section elementor-top-section elementor-element elementor-element-7c0a3d18 elementor-section-full_width elementor-section-height-min-height elementor-section-stretched elementor-section-height-default elementor-section-items-middle\" data-id=\"7c0a3d18\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1235f49e\" data-id=\"1235f49e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3b88fc7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3b88fc7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3178b67b\" data-id=\"3178b67b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c828874 elementor-tabs-view-vertical elementor-widget elementor-widget-tabs\" data-id=\"2c828874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7461\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7461\" aria-expanded=\"false\">\u00bfA qui\u00e9n va digido?<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7462\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7462\" aria-expanded=\"false\">Direcci\u00f3n del curso<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7463\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7463\" aria-expanded=\"false\">Metodolog\u00eda y evaluaci\u00f3n<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-7464\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7464\" aria-expanded=\"false\">Resultado del aprendizaje<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-7461\" aria-expanded=\"false\">\u00bfA qui\u00e9n va digido?<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7461\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7461\" tabindex=\"0\" hidden=\"false\"><h4>Perfil del alumnado<\/h4><ul><li>Auditores Internos, Directores y Responsables de Medio Ambiente.<\/li><li>Personal con conocimientos de la norma ISO 14001.<\/li><li>Profesionales de diversa \u00edndole interesadas en estar materias.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7462\" aria-expanded=\"false\">Direcci\u00f3n del curso<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7462\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7462\" tabindex=\"0\" hidden=\"hidden\"><p><span style=\"color: #00335b;\">Direcci\u00f3n acad\u00e9mica<\/span><\/p><ul><li><strong>Mar\u00eda del Carmen Correa Ruiz<\/strong>, profesora titular Universidad Pablo de Olavide.<\/li><\/ul><p><span style=\"color: #00335b;\">Direcci\u00f3n ejecutiva<\/span><\/p><ul><li><strong>Bel\u00e9n Mac\u00edas Calero<\/strong>, jefa de estudios de Bureau Veritas Formaci\u00f3n.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7463\" aria-expanded=\"false\">Metodolog\u00eda y evaluaci\u00f3n<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7463\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7463\" tabindex=\"0\" hidden=\"hidden\"><h4>Metodolog\u00eda<\/h4><p>Bureau Veritas ofrece a los alumnos realizar un curso online previo al curso AUDITOR JEFE IRCA y que pone a su disposici\u00f3n los conocimientos y conceptos b\u00e1sicos de la norma objeto de estudio que facilitar\u00e1n un mejor aprovechamiento de la parte presencial AUDITOR JEFE IRCA. A este Curso se tendr\u00e1 acceso con antelaci\u00f3n al inicio de la parte presencial AUDITOR JEFE IRCA con el fin de que los alumnos hayan finalizado esta parte antes del comienzo de la semana presencial.<\/p><p>Las sesiones presenciales integran la parte te\u00f3rica en la parte pr\u00e1ctica de un modo din\u00e1mico a trav\u00e9s de debates, casos reales y otros ejercicios.<\/p><p>Los casos que se ven en el curso presencial hacen referencia a una empresa ficticia, sin embargo, los procedimientos, instrucciones de trabajo y datos podr\u00edan corresponderse con los de empresas reales.\u00a0<\/p><p>Los ejercicios pr\u00e1cticos han sido cuidadosamente dise\u00f1ados para centrarse en temas que surgen com\u00fanmente durante las auditor\u00edas a sistemas de gesti\u00f3n de la calidad.<\/p><h4>Evaluaci\u00f3n<\/h4><p>El modo de evaluaci\u00f3n de la formaci\u00f3n AUDITOR JEFE IRCA, parte Elearning, se lleva a cabo a trav\u00e9s de un Test de evaluaci\u00f3n que deber\u00e1 realizarse tras el estudio de cada Unidad, con un total de 6 Unidades de estudio. Adem\u00e1s, los alumnos tendr\u00e1n a su disposici\u00f3n actividades de autoevaluaci\u00f3n por cada Unidad que les ayudar\u00e1n a reforzar sus conocimientos y podr\u00e1n realizar el n\u00famero de veces que consideren oportuno.<\/p><p>En cuanto al modo de evaluaci\u00f3n en la formaci\u00f3n AUDITOR JEFE IRCA, parte PRESENCIAL, hay que tener en cuenta dos partes que deben ser evaluadas y superadas para obtener el certificado oficial de aprovechamiento correspondiente:<\/p><ol><li>La evaluaci\u00f3n continua realizada a lo largo de toda la semana de la formaci\u00f3n presencial a trav\u00e9s de actividades desarrolladas durante los d\u00edas de formaci\u00f3n.<\/li><li>Examen.<\/li><\/ol><p>El certificado con acreditaci\u00f3n IRCA s\u00f3lo ser\u00e1 emitido si han sido superadas ambas partes de la semana presencial (evaluaci\u00f3n continua y examen).<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"4\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-7464\" aria-expanded=\"false\">Resultado del aprendizaje<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7464\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7464\" tabindex=\"0\" hidden=\"hidden\"><ul><li>Comprender el prop\u00f3sito de un sistema de gesti\u00f3n ambiental en base a la norma ISO 14001, la auditor\u00eda del sistema, la certificaci\u00f3n de tercera parte y los beneficios de un mejor desempe\u00f1o del sistema de gesti\u00f3n ambiental.<\/li><li>Comprender los roles, funciones y responsabilidades de un equipo auditor para planificar, llevar a cabo, concluir, informar y hacer un seguimiento de una auditor\u00eda al sistema de gesti\u00f3n ambiental de acuerdo con ISO 14001 e ISO\/ IEC 17021, seg\u00fan corresponda.<\/li><li>Planificar, llevar a cabo, informar y hacer seguimiento a una auditor\u00eda al sistema de gesti\u00f3n ambiental para establecer conformidad (o de otro modo) con ISO 14001 y de acuerdo con ISO 19011 e ISO \/ IEC 17021, seg\u00fan corresponda.<\/li><\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-476989f elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"476989f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7793fa0f\" data-id=\"7793fa0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#00335B\" class=\"elementor-element elementor-element-49f9887c elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-widget elementor-widget-global elementor-global-16089 elementor-widget-call-to-action\" data-id=\"49f9887c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/pdfs\/microcredenciales\/2023ci29.pdf\" target=\"_blank\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url();\" role=\"img\" aria-label=\"\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tDescargar el programa\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tDescarga el programa completo del curso en PDF\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-xs\">\n\t\t\t\t\t\tDescargar PDF\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-1cc5629e\" data-id=\"1cc5629e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#00335B\" class=\"elementor-element elementor-element-54f44da5 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-widget elementor-widget-call-to-action\" data-id=\"54f44da5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2022\/10\/microcredencial-2.jpg);\" role=\"img\" aria-label=\"microcredencial-2\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tNivel MECES*\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tNivel MECES 1 - EQF 5 (T\u00e9cnico Superior de Formaci\u00f3n Profesional)  *Marco Espa\u00f1ol de Cualificaciones para la Educaci\u00f3n Superior\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7facb095\" data-id=\"7facb095\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#00335B\" class=\"elementor-element elementor-element-35364543 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-widget elementor-widget-call-to-action\" data-id=\"35364543\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE1NzcwIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2022\/10\/microcredenciales-3.jpg);\" role=\"img\" aria-label=\"microcredenciales-3\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tProcedimiento de calidad\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tConsulta la pol\u00edtica de calidad de las microcrendenciales\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-xs\">\n\t\t\t\t\t\tM\u00e1s informaci\u00f3n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3d2f03c4\" data-id=\"3d2f03c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-title-color=\"#00335B\" class=\"elementor-element elementor-element-6bec8165 elementor-cta--skin-cover elementor-cta--valign-middle elementor-bg-transform elementor-bg-transform-zoom-out elementor-widget elementor-widget-call-to-action\" data-id=\"6bec8165\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a class=\"elementor-cta\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE1NzQxIiwidG9nZ2xlIjpmYWxzZX0%3D\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2022\/10\/microcredenciales-1.jpg);\" role=\"img\" aria-label=\"microcredenciales-1\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t\u00bfNecesitas m\u00e1s informaci\u00f3n?\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tSolicita m\u00e1s informaci\u00f3n para sobre esta microcredencial\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<span class=\"elementor-cta__button elementor-button elementor-size-xs\">\n\t\t\t\t\t\tSolicitar\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-384c2407 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"384c2407\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;sticky&quot;:&quot;bottom&quot;,&quot;sticky_on&quot;:[&quot;mobile&quot;],&quot;sticky_offset_mobile&quot;:20,&quot;sticky_effects_offset_mobile&quot;:0,&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b0508ab\" data-id=\"3b0508ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div data-dce-background-color=\"#FAB54C\" class=\"elementor-element elementor-element-77f7965 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"77f7965\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;bottom&quot;,&quot;sticky_on&quot;:[&quot;mobile&quot;],&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.upo.es\/automat-fund\/web\/index.php?r=curso%2Fview&#038;id=96\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Acceso a la matriculaci\u00f3n<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":17087,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categories":[63,52],"titulos_propios":[],"class_list":["post-17074","microcredenciales","type-microcredenciales","status-publish","has-post-thumbnail","hentry","category-2023-2024","category-matricula-cerrada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912) - Formaci\u00f3n Permanente UPO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912) - Formaci\u00f3n Permanente UPO\" \/>\n<meta property=\"og:description\" content=\"Microcredencial Matr\u00edcula cerrada Presentaci\u00f3n El curso Auditor Jefe de Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 acreditado por el Registro Internacional de Auditores Certificados (IRCA) aporta los conocimientos necesarios para auditar cualquier tipo de organizaci\u00f3n en base a los est\u00e1ndares de la Norma ISO. El curso es impartido por profesores altamente cualificados, con amplia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/\" \/>\n<meta property=\"og:site_name\" content=\"Formaci\u00f3n Permanente UPO\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-03T10:29:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/01\/2023ci29-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/\",\"url\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/\",\"name\":\"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912) - Formaci\u00f3n Permanente UPO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/wp-content\\\/imagenes\\\/uploads\\\/2023\\\/01\\\/2023ci29-scaled.jpg\",\"datePublished\":\"2023-01-30T11:37:56+00:00\",\"dateModified\":\"2023-10-03T10:29:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/wp-content\\\/imagenes\\\/uploads\\\/2023\\\/01\\\/2023ci29-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/wp-content\\\/imagenes\\\/uploads\\\/2023\\\/01\\\/2023ci29-scaled.jpg\",\"width\":2560,\"height\":1493,\"caption\":\"2023ci29\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/microcredenciales\\\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/#website\",\"url\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/\",\"name\":\"Formaci\u00f3n Permanente UPO\",\"description\":\"T\u00edtulos Propios, Microcredenciales, Cursos de Verano\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/#organization\",\"name\":\"Formaci\u00f3n Permanente Universidad Pablo de Olavide\",\"alternateName\":\"Formaci\u00f3n Permanente UPO\",\"url\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/wp-content\\\/imagenes\\\/uploads\\\/2023\\\/02\\\/Logo-UPO-azul-amarillo-horizontal.png\",\"contentUrl\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/wp-content\\\/imagenes\\\/uploads\\\/2023\\\/02\\\/Logo-UPO-azul-amarillo-horizontal.png\",\"width\":1000,\"height\":407,\"caption\":\"Formaci\u00f3n Permanente Universidad Pablo de Olavide\"},\"image\":{\"@id\":\"https:\\\/\\\/www.upo.es\\\/formacionpermanente\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912) - Formaci\u00f3n Permanente UPO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/","og_locale":"es_ES","og_type":"article","og_title":"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912) - Formaci\u00f3n Permanente UPO","og_description":"Microcredencial Matr\u00edcula cerrada Presentaci\u00f3n El curso Auditor Jefe de Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 acreditado por el Registro Internacional de Auditores Certificados (IRCA) aporta los conocimientos necesarios para auditar cualquier tipo de organizaci\u00f3n en base a los est\u00e1ndares de la Norma ISO. El curso es impartido por profesores altamente cualificados, con amplia [&hellip;]","og_url":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/","og_site_name":"Formaci\u00f3n Permanente UPO","article_modified_time":"2023-10-03T10:29:36+00:00","og_image":[{"width":2560,"height":1493,"url":"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/01\/2023ci29-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/","url":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/","name":"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912) - Formaci\u00f3n Permanente UPO","isPartOf":{"@id":"https:\/\/www.upo.es\/formacionpermanente\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/#primaryimage"},"image":{"@id":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/#primaryimage"},"thumbnailUrl":"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/01\/2023ci29-scaled.jpg","datePublished":"2023-01-30T11:37:56+00:00","dateModified":"2023-10-03T10:29:36+00:00","breadcrumb":{"@id":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/#primaryimage","url":"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/01\/2023ci29-scaled.jpg","contentUrl":"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/01\/2023ci29-scaled.jpg","width":2560,"height":1493,"caption":"2023ci29"},{"@type":"BreadcrumbList","@id":"https:\/\/www.upo.es\/formacionpermanente\/microcredenciales\/auditor-jefe-certificacion-sistemas-de-gestion-de-medio-ambiente-iso-140012015-irca-17912\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.upo.es\/formacionpermanente\/"},{"@type":"ListItem","position":2,"name":"Auditor Jefe Certificaci\u00f3n Sistemas de Gesti\u00f3n de Medio Ambiente ISO 14001:2015 (IRCA 17912)"}]},{"@type":"WebSite","@id":"https:\/\/www.upo.es\/formacionpermanente\/#website","url":"https:\/\/www.upo.es\/formacionpermanente\/","name":"Formaci\u00f3n Permanente UPO","description":"T\u00edtulos Propios, Microcredenciales, Cursos de Verano","publisher":{"@id":"https:\/\/www.upo.es\/formacionpermanente\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.upo.es\/formacionpermanente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.upo.es\/formacionpermanente\/#organization","name":"Formaci\u00f3n Permanente Universidad Pablo de Olavide","alternateName":"Formaci\u00f3n Permanente UPO","url":"https:\/\/www.upo.es\/formacionpermanente\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.upo.es\/formacionpermanente\/#\/schema\/logo\/image\/","url":"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/02\/Logo-UPO-azul-amarillo-horizontal.png","contentUrl":"https:\/\/www.upo.es\/formacionpermanente\/wp-content\/imagenes\/uploads\/2023\/02\/Logo-UPO-azul-amarillo-horizontal.png","width":1000,"height":407,"caption":"Formaci\u00f3n Permanente Universidad Pablo de Olavide"},"image":{"@id":"https:\/\/www.upo.es\/formacionpermanente\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/microcredenciales\/17074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/microcredenciales"}],"about":[{"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/types\/microcredenciales"}],"version-history":[{"count":2,"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/microcredenciales\/17074\/revisions"}],"predecessor-version":[{"id":27624,"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/microcredenciales\/17074\/revisions\/27624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/media\/17087"}],"wp:attachment":[{"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/media?parent=17074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/categories?post=17074"},{"taxonomy":"titulos_propios","embeddable":true,"href":"https:\/\/www.upo.es\/formacionpermanente\/wp-json\/wp\/v2\/titulos_propios?post=17074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}